{"id":15236,"date":"2025-05-05T09:55:08","date_gmt":"2025-05-05T07:55:08","guid":{"rendered":"httpsss:\/\/dev.b-w-cases-of-success.de\/produkt\/media-bag-tex-210-rpd-laptop-bag-with-variable-compartments\/"},"modified":"2025-08-27T14:06:56","modified_gmt":"2025-08-27T12:06:56","slug":"bw-bag-tex-210-rpd","status":"publish","type":"product","link":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/bw-bag-tex-210-rpd\/","title":{"rendered":"bw.bag TEX.210.RPD | Laptop bag with variable compartments"},"content":{"rendered":"<div>\n<ul>\n<li>Water-repellent soft bag made of polyester<\/li>\n<li>Easy to open 2-way zipper<\/li>\n<li>Variable compartment division (RPD)<\/li>\n<li>Two mesh pockets<\/li>\n<li>One front compartment<\/li>\n<li>Fits into the B&amp;W transport case bw.case PP.117<\/li>\n<li>Laptop compartment bag: 320 x 330 x 65 mm<\/li>\n<\/ul>\n<\/div>\n<div style=\"display:flex; gap:10px;justify-content:center\" class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend\">\n\t\t<a  href=\"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product\/15236\/?action=genpdf&amp;id=15236\" class=\"pgfw-single-pdf-download-button\" target=_blank><img src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/icon-download.svg\" title=\"Generate PDF\" style=\"width:auto; height:45px;\"><\/a>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Water-repellent soft bag made of polyester Easy to open 2-way zipper Variable compartment division (RPD) Two mesh pockets One front compartment Fits into the B&amp;W transport case bw.case PP.117 Laptop compartment bag: 320 x 330 x 65 mm<\/p>\n","protected":false},"featured_media":13126,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[169,405],"product_tag":[],"class_list":["post-15236","product","type-product","status-publish","has-post-thumbnail","product_cat-accessories-multipurpase","product_cat-accessories-photo-video","pa_farbe-anthracite","first","instock","product-type-simple"],"acf":[],"yoast_head":"<title>bw.bag TEX.210.RPD | Laptop bag with variable compartments - B&amp;W Cases of Success<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/bw-bag-tex-210-rpd\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"bw.bag TEX.210.RPD | Laptop bag with variable compartments - B&amp;W Cases of Success\" \/>\n<meta property=\"og:description\" content=\"Water-repellent soft bag made of polyester Easy to open 2-way zipper Variable compartment division (RPD) Two mesh pockets One front compartment Fits into the B&amp;W transport case bw.case PP.117 Laptop compartment bag: 320 x 330 x 65 mm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/bw-bag-tex-210-rpd\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-27T12:06:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/6040_tex-210_media-bag-with-belt_bw-international.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/bw-bag-tex-210-rpd\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/bw-bag-tex-210-rpd\\\/\",\"name\":\"bw.bag TEX.210.RPD | Laptop bag with variable compartments - B&amp;W Cases of Success\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/bw-bag-tex-210-rpd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/bw-bag-tex-210-rpd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/6040_tex-210_media-bag-with-belt_bw-international.jpg\",\"datePublished\":\"2025-05-05T07:55:08+00:00\",\"dateModified\":\"2025-08-27T12:06:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/bw-bag-tex-210-rpd\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/bw-bag-tex-210-rpd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/bw-bag-tex-210-rpd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/6040_tex-210_media-bag-with-belt_bw-international.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/6040_tex-210_media-bag-with-belt_bw-international.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"Graue B&W International tex 210 Umh\u00e4ngetasche mit Tragegriff und abnehmbarem Schultergurt \u2013 ideal f\u00fcr Laptop oder mobiles Equipment.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/bw-bag-tex-210-rpd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/home-page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Multipurpose cases\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkte\\\/multipurpose-cases\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Accessories\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkte\\\/multipurpose-cases\\\/accessories-multipurpase\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"bw.bag TEX.210.RPD | Laptop bag with variable compartments\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"bw.bag TEX.210.RPD | Laptop bag with variable compartments - B&amp;W Cases of Success","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/bw-bag-tex-210-rpd\/","og_locale":"en_US","og_type":"article","og_title":"bw.bag TEX.210.RPD | Laptop bag with variable compartments - B&amp;W Cases of Success","og_description":"Water-repellent soft bag made of polyester Easy to open 2-way zipper Variable compartment division (RPD) Two mesh pockets One front compartment Fits into the B&amp;W transport case bw.case PP.117 Laptop compartment bag: 320 x 330 x 65 mm","og_url":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/bw-bag-tex-210-rpd\/","og_site_name":"B&amp;W Cases of Success","article_modified_time":"2025-08-27T12:06:56+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/6040_tex-210_media-bag-with-belt_bw-international.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/bw-bag-tex-210-rpd\/","url":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/bw-bag-tex-210-rpd\/","name":"bw.bag TEX.210.RPD | Laptop bag with variable compartments - B&amp;W Cases of Success","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/bw-bag-tex-210-rpd\/#primaryimage"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/bw-bag-tex-210-rpd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/6040_tex-210_media-bag-with-belt_bw-international.jpg","datePublished":"2025-05-05T07:55:08+00:00","dateModified":"2025-08-27T12:06:56+00:00","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/bw-bag-tex-210-rpd\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/bw-bag-tex-210-rpd\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/bw-bag-tex-210-rpd\/#primaryimage","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/6040_tex-210_media-bag-with-belt_bw-international.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/6040_tex-210_media-bag-with-belt_bw-international.jpg","width":1920,"height":1920,"caption":"Graue B&W International tex 210 Umh\u00e4ngetasche mit Tragegriff und abnehmbarem Schultergurt \u2013 ideal f\u00fcr Laptop oder mobiles Equipment."},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/bw-bag-tex-210-rpd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/en\/home-page\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.b-w-cases-of-success.com\/en\/products\/"},{"@type":"ListItem","position":3,"name":"Multipurpose cases","item":"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/multipurpose-cases\/"},{"@type":"ListItem","position":4,"name":"Accessories","item":"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/multipurpose-cases\/accessories-multipurpase\/"},{"@type":"ListItem","position":5,"name":"bw.bag TEX.210.RPD | Laptop bag with variable compartments"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/en\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product\/15236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/media?parent=15236"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product_brand?post=15236"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product_cat?post=15236"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product_tag?post=15236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}