{"id":24689,"date":"2026-02-06T11:04:12","date_gmt":"2026-02-06T10:04:12","guid":{"rendered":"httpsss:\/\/dev.b-w-cases-of-success.de\/?post_type=product&#038;p=24689"},"modified":"2026-06-24T10:39:55","modified_gmt":"2026-06-24T08:39:55","slug":"cargo-case-hdpe-1376-2025","status":"publish","type":"product","link":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/cargo-case-hdpe-1376-2025\/","title":{"rendered":"cargo.case PE 1376.2025 | B&amp;W Cargo case in many sizes"},"content":{"rendered":"<div>\n<ul>\n<li>Extremely robust case frame made of impact-resistant high-performance PE<\/li>\n<li>Heavy-duty polymer handles with ergonomic rubber grip<\/li>\n<li>Durable, heavy-duty stainless steel fasteners<\/li>\n<li>Waterproof silicone seal between case frame and lid<\/li>\n<li>Particularly resistant to shocks and vibrations<\/li>\n<li>UV-resistant and chemical-resistant<\/li>\n<li>Optionally with robust edge rollers for easy handling<\/li>\n<li>Designed for extreme temperatures and intense sunlight<\/li>\n<li>Customized interior fittings and inlays available<\/li>\n<li>Various color options available<\/li>\n<li>Straight or crosswise stacking &#8211; even with different case sizes<\/li>\n<li>Certified according to MIL-STD-810G, DEF STAN 81-41, STANAG 4280<\/li>\n<li>Dust and waterproof according to IP67<\/li>\n<\/ul>\n<p>The cargo.cases are also available in other colors on request.<br \/>\nYou can find a complete overview of all available sizes and configurations in our <a href=\"https:\/\/dev.b-w-cases-of-success.de\/en\/?attachment_id=24601\" target=\"_blank\" rel=\"noopener\"><strong>product overview<\/strong><\/a>.<\/p>\n<\/div>\n<div style=\"display:flex; gap:10px;justify-content:center\" class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend\">\n\t\t<a  href=\"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product\/24689\/?action=genpdf&amp;id=24689\" class=\"pgfw-single-pdf-download-button\" target=_blank><img src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/icon-download.svg\" title=\"Generate PDF\" style=\"width:auto; height:45px;\"><\/a>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Extremely robust case frame made of impact-resistant high-performance PE Heavy-duty polymer handles with ergonomic rubber grip Durable, heavy-duty stainless steel fasteners Waterproof silicone seal between case frame and lid Particularly resistant to shocks and vibrations UV-resistant and chemical-resistant Optionally with robust edge rollers for easy handling Designed for extreme temperatures and intense sunlight Customized interior [&hellip;]<\/p>\n","protected":false},"featured_media":24699,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[877,855],"product_tag":[],"class_list":["post-24689","product","type-product","status-publish","has-post-thumbnail","product_features-impact-and-shock-resistant","product_features-resistant-material","product_features-stackable","product_cat-cargo","product_cat-cargo-case","pa_farbe-black","pa_farbe-bronze-green","pa_farbe-orange-en","pa_farbe-yellow","first","instock","product-type-variable"],"acf":[],"yoast_head":"<title>cargo.case PE 1376.2025 | B&amp;W Cargo case in many sizes - B&amp;W Cases of Success<\/title>\n<meta name=\"description\" content=\"Handy B&amp;W multi-purpose case \u2713Shockproof \u2713Waterproof \u2713With carrying handle \u2713Secure closure \u2794 Get advice now!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/cargo-case-hdpe-1376-2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cargo.case PE 1376.2025 | B&amp;W Cargo case in many sizes - B&amp;W Cases of Success\" \/>\n<meta property=\"og:description\" content=\"Handy B&amp;W multi-purpose case \u2713Shockproof \u2713Waterproof \u2713With carrying handle \u2713Secure closure \u2794 Get advice now!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/cargo-case-hdpe-1376-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T08:39:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-1376-2025_closed_bw-international.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/cargo-case-hdpe-1376-2025\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/cargo-case-hdpe-1376-2025\\\/\",\"name\":\"cargo.case PE 1376.2025 | B&amp;W Cargo case in many sizes - B&amp;W Cases of Success\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/cargo-case-hdpe-1376-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/cargo-case-hdpe-1376-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cargo-case_HDPE-1376-2025_closed_bw-international.jpg\",\"datePublished\":\"2026-02-06T10:04:12+00:00\",\"dateModified\":\"2026-06-24T08:39:55+00:00\",\"description\":\"Handy B&W multi-purpose case \u2713Shockproof \u2713Waterproof \u2713With carrying handle \u2713Secure closure \u2794 Get advice now!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/cargo-case-hdpe-1376-2025\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/cargo-case-hdpe-1376-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/cargo-case-hdpe-1376-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cargo-case_HDPE-1376-2025_closed_bw-international.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cargo-case_HDPE-1376-2025_closed_bw-international.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"A large, black B&amp;W cargo.case HDPE 1376.2025 hard case with reinforced edges and several closures is shown on a white background.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/cargo-case-hdpe-1376-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/home-page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Transport cases\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkte\\\/transport-cases\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cargo cases\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkte\\\/transport-cases\\\/cargo-case\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"cargo.case PE 1376.2025 | B&amp;W Cargo case in many sizes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"cargo.case PE 1376.2025 | B&amp;W Cargo case in many sizes - B&amp;W Cases of Success","description":"Handy B&W multi-purpose case \u2713Shockproof \u2713Waterproof \u2713With carrying handle \u2713Secure closure \u2794 Get advice now!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/cargo-case-hdpe-1376-2025\/","og_locale":"en_US","og_type":"article","og_title":"cargo.case PE 1376.2025 | B&amp;W Cargo case in many sizes - B&amp;W Cases of Success","og_description":"Handy B&W multi-purpose case \u2713Shockproof \u2713Waterproof \u2713With carrying handle \u2713Secure closure \u2794 Get advice now!","og_url":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/cargo-case-hdpe-1376-2025\/","og_site_name":"B&amp;W Cases of Success","article_modified_time":"2026-06-24T08:39:55+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-1376-2025_closed_bw-international.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/cargo-case-hdpe-1376-2025\/","url":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/cargo-case-hdpe-1376-2025\/","name":"cargo.case PE 1376.2025 | B&amp;W Cargo case in many sizes - B&amp;W Cases of Success","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/cargo-case-hdpe-1376-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/cargo-case-hdpe-1376-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-1376-2025_closed_bw-international.jpg","datePublished":"2026-02-06T10:04:12+00:00","dateModified":"2026-06-24T08:39:55+00:00","description":"Handy B&W multi-purpose case \u2713Shockproof \u2713Waterproof \u2713With carrying handle \u2713Secure closure \u2794 Get advice now!","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/cargo-case-hdpe-1376-2025\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/cargo-case-hdpe-1376-2025\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/cargo-case-hdpe-1376-2025\/#primaryimage","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-1376-2025_closed_bw-international.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-1376-2025_closed_bw-international.jpg","width":1920,"height":1920,"caption":"A large, black B&amp;W cargo.case HDPE 1376.2025 hard case with reinforced edges and several closures is shown on a white background."},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/cargo-case-hdpe-1376-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/en\/home-page\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.b-w-cases-of-success.com\/en\/products\/"},{"@type":"ListItem","position":3,"name":"Transport cases","item":"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/transport-cases\/"},{"@type":"ListItem","position":4,"name":"Cargo cases","item":"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/transport-cases\/cargo-case\/"},{"@type":"ListItem","position":5,"name":"cargo.case PE 1376.2025 | B&amp;W Cargo case in many sizes"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/en\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product\/24689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/media\/24699"}],"wp:attachment":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/media?parent=24689"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product_brand?post=24689"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product_cat?post=24689"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product_tag?post=24689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}