{"id":27532,"date":"2026-05-07T09:58:55","date_gmt":"2026-05-07T07:58:55","guid":{"rendered":"httpsss:\/\/dev.b-w-cases-of-success.de\/?post_type=product&#038;p=27532"},"modified":"2026-05-07T10:29:51","modified_gmt":"2026-05-07T08:29:51","slug":"mega-case-pp-212","status":"publish","type":"product","link":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/mega-case-pp-212\/","title":{"rendered":"Mega.case PP.212 I B&amp;W Megabag 2000"},"content":{"rendered":"<ul>\n<li>4 sizes<\/li>\n<li>Double-walled<\/li>\n<li>Scratch-resistant textured surface<\/li>\n<li>High load capacity<\/li>\n<li>Folding handle<\/li>\n<li>Integrated reinforcement on the handle side<\/li>\n<li>Proven film hinges<\/li>\n<li>Separate combination lock<\/li>\n<li>Customizable inner core<\/li>\n<\/ul>\n<div style=\"display:flex; gap:10px;justify-content:center\" class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend\">\n\t\t<a  href=\"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product\/27532\/?action=genpdf&amp;id=27532\" class=\"pgfw-single-pdf-download-button\" target=_blank><img src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/icon-download.svg\" title=\"Generate PDF\" style=\"width:auto; height:45px;\"><\/a>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>4 sizes Double-walled Scratch-resistant textured surface High load capacity Folding handle Integrated reinforcement on the handle side Proven film hinges Separate combination lock Customizable inner core<\/p>\n","protected":false},"featured_media":27539,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[884],"product_tag":[],"class_list":["post-27532","product","type-product","status-publish","has-post-thumbnail","product_cat-presentation-case","pa_farbe-black","first","instock","shipping-taxable","product-type-variable"],"acf":[],"yoast_head":"<title>Mega.case PP.212 I B&amp;W Megabag 2000 - B&amp;W Cases of Success<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/mega-case-pp-212\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mega.case PP.212 I B&amp;W Megabag 2000 - B&amp;W Cases of Success\" \/>\n<meta property=\"og:description\" content=\"4 sizes Double-walled Scratch-resistant textured surface High load capacity Folding handle Integrated reinforcement on the handle side Proven film hinges Separate combination lock Customizable inner core\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/mega-case-pp-212\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T08:29:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/05\/Mega-case_2000_B_closed-standing_bw-international.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/mega-case-pp-212\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/mega-case-pp-212\\\/\",\"name\":\"Mega.case PP.212 I B&amp;W Megabag 2000 - B&amp;W Cases of Success\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/mega-case-pp-212\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/mega-case-pp-212\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Mega-case_2000_B_closed-standing_bw-international.jpg\",\"datePublished\":\"2026-05-07T07:58:55+00:00\",\"dateModified\":\"2026-05-07T08:29:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/mega-case-pp-212\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/mega-case-pp-212\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/mega-case-pp-212\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Mega-case_2000_B_closed-standing_bw-international.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Mega-case_2000_B_closed-standing_bw-international.jpg\",\"width\":1920,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkt\\\/mega-case-pp-212\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/home-page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Presentation case\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkte\\\/presentation-case\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Mega.case PP.212 I B&amp;W Megabag 2000\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"Mega.case PP.212 I B&amp;W Megabag 2000 - B&amp;W Cases of Success","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/mega-case-pp-212\/","og_locale":"en_US","og_type":"article","og_title":"Mega.case PP.212 I B&amp;W Megabag 2000 - B&amp;W Cases of Success","og_description":"4 sizes Double-walled Scratch-resistant textured surface High load capacity Folding handle Integrated reinforcement on the handle side Proven film hinges Separate combination lock Customizable inner core","og_url":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/mega-case-pp-212\/","og_site_name":"B&amp;W Cases of Success","article_modified_time":"2026-05-07T08:29:51+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/05\/Mega-case_2000_B_closed-standing_bw-international.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/mega-case-pp-212\/","url":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/mega-case-pp-212\/","name":"Mega.case PP.212 I B&amp;W Megabag 2000 - B&amp;W Cases of Success","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/mega-case-pp-212\/#primaryimage"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/mega-case-pp-212\/#primaryimage"},"thumbnailUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/05\/Mega-case_2000_B_closed-standing_bw-international.jpg","datePublished":"2026-05-07T07:58:55+00:00","dateModified":"2026-05-07T08:29:51+00:00","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/mega-case-pp-212\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/mega-case-pp-212\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/mega-case-pp-212\/#primaryimage","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/05\/Mega-case_2000_B_closed-standing_bw-international.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/05\/Mega-case_2000_B_closed-standing_bw-international.jpg","width":1920,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkt\/mega-case-pp-212\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/en\/home-page\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.b-w-cases-of-success.com\/en\/products\/"},{"@type":"ListItem","position":3,"name":"Presentation case","item":"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/presentation-case\/"},{"@type":"ListItem","position":4,"name":"Mega.case PP.212 I B&amp;W Megabag 2000"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/en\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product\/27532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/media\/27539"}],"wp:attachment":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/media?parent=27532"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product_brand?post=27532"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product_cat?post=27532"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product_tag?post=27532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}