{"id":877,"count":14,"description":"","link":"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/cargo\/","name":"Cargo case","slug":"cargo","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":21,"acf":[],"yoast_head":"<title>Cargokoffer von B&amp;W | Robuste Transportl\u00f6sungen<\/title>\n<meta name=\"description\" content=\"Empfindliche Ausr\u00fcstung sicher transportieren \u2713 Cargokoffer von B&amp;W sch\u00fctzen Equipment in Industrie, Milit\u00e4r &amp; Logistik. Jetzt L\u00f6sungen entdecken.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/cargo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cargokoffer von B&amp;W | Robuste Transportl\u00f6sungen\" \/>\n<meta property=\"og:description\" content=\"Empfindliche Ausr\u00fcstung sicher transportieren \u2713 Cargokoffer von B&amp;W sch\u00fctzen Equipment in Industrie, Milit\u00e4r &amp; Logistik. Jetzt L\u00f6sungen entdecken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/cargo\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1067\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkte\\\/cargo\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkte\\\/cargo\\\/\",\"name\":\"Cargokoffer von B&W | Robuste Transportl\u00f6sungen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#website\"},\"description\":\"Empfindliche Ausr\u00fcstung sicher transportieren \u2713 Cargokoffer von B&W sch\u00fctzen Equipment in Industrie, Milit\u00e4r & Logistik. Jetzt L\u00f6sungen entdecken.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkte\\\/cargo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/produkte\\\/cargo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/home-page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cargo case\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"Cargokoffer von B&W | Robuste Transportl\u00f6sungen","description":"Empfindliche Ausr\u00fcstung sicher transportieren \u2713 Cargokoffer von B&W sch\u00fctzen Equipment in Industrie, Milit\u00e4r & Logistik. Jetzt L\u00f6sungen entdecken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/cargo\/","og_locale":"en_US","og_type":"article","og_title":"Cargokoffer von B&W | Robuste Transportl\u00f6sungen","og_description":"Empfindliche Ausr\u00fcstung sicher transportieren \u2713 Cargokoffer von B&W sch\u00fctzen Equipment in Industrie, Milit\u00e4r & Logistik. Jetzt L\u00f6sungen entdecken.","og_url":"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/cargo\/","og_site_name":"B&amp;W Cases of Success","og_image":[{"width":1067,"height":1067,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/cargo\/","url":"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/cargo\/","name":"Cargokoffer von B&W | Robuste Transportl\u00f6sungen","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#website"},"description":"Empfindliche Ausr\u00fcstung sicher transportieren \u2713 Cargokoffer von B&W sch\u00fctzen Equipment in Industrie, Milit\u00e4r & Logistik. Jetzt L\u00f6sungen entdecken.","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/cargo\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/produkte\/cargo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/en\/home-page\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.b-w-cases-of-success.com\/en\/products\/"},{"@type":"ListItem","position":3,"name":"Cargo case"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/en\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product_cat\/877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.b-w-cases-of-success.com\/en\/wp-json\/wp\/v2\/product?product_cat=877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}