{"id":25056,"date":"2026-02-11T10:47:55","date_gmt":"2026-02-11T09:47:55","guid":{"rendered":"httpsss:\/\/dev.b-w-cases-of-success.de\/?post_type=product&#038;p=25056"},"modified":"2026-06-24T10:34:22","modified_gmt":"2026-06-24T08:34:22","slug":"cargo-case-hdpe-19975-5852f","status":"publish","type":"product","link":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/cargo-case-hdpe-19975-5852f\/","title":{"rendered":"cargo.case PE 19975.5852F | Maleta de carga B&amp;W en muchos tama\u00f1os"},"content":{"rendered":"<div>\n<ul>\n<li>Armaz\u00f3n extremadamente robusto de PE de alto rendimiento resistente a los golpes<\/li>\n<li>Mangos de pol\u00edmero de alta resistencia con empu\u00f1adura ergon\u00f3mica de goma<\/li>\n<li>Cierres de acero inoxidable duraderos y resistentes<\/li>\n<li>Junta de silicona impermeable entre el marco del malet\u00edn y la tapa<\/li>\n<li>Especialmente resistente a golpes y vibraciones<\/li>\n<li>Resistente a los rayos UV y a los productos qu\u00edmicos<\/li>\n<li>Opcionalmente con rodillos robustos en los bordes para facilitar la manipulaci\u00f3n<\/li>\n<li>Dise\u00f1ado para temperaturas extremas y luz solar intensa<\/li>\n<li>Accesorios interiores e incrustaciones personalizados disponibles<\/li>\n<li>Varios colores disponibles<\/li>\n<li>Apilado recto o transversal, incluso con diferentes tama\u00f1os de cajas<\/li>\n<li>Certificado seg\u00fan MIL-STD-810G, DEF STAN 81-41, STANAG 4280<\/li>\n<li>Resistente al polvo y al agua seg\u00fan IP67<\/li>\n<\/ul>\n<p>Los maletines de carga tambi\u00e9n est\u00e1n disponibles en otros colores bajo pedido.<br \/>\nPuedes encontrar una visi\u00f3n completa de todos los tama\u00f1os y configuraciones disponibles en nuestra <a href=\"https:\/\/dev.b-w-cases-of-success.de\/es\/?attachment_id=24601\" target=\"_blank\" rel=\"noopener\"><strong>resumen de productos<\/strong><\/a>.<\/p>\n<\/div>\n<div style=\"display:flex; gap:10px;justify-content:center\" class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend\">\n\t\t<a  href=\"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product\/25056\/?action=genpdf&amp;id=25056\" class=\"pgfw-single-pdf-download-button\" target=_blank><img src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/icon-download.svg\" title=\"Generar PDF\" style=\"width:auto; height:45px;\"><\/a>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Armaz\u00f3n extremadamente robusto de PE de alto rendimiento resistente a los golpes Mangos de pol\u00edmero de alta resistencia con empu\u00f1adura ergon\u00f3mica de goma Cierres de acero inoxidable duraderos y resistentes Junta de silicona impermeable entre el marco del malet\u00edn y la tapa Especialmente resistente a golpes y vibraciones Resistente a los rayos UV y a [&hellip;]<\/p>\n","protected":false},"featured_media":25063,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[857,879],"product_tag":[],"class_list":["post-25056","product","type-product","status-publish","has-post-thumbnail","product_features-apilable","product_features-extremadamente-resistente","product_features-material-resistente","product_cat-cargo-case","product_cat-cargo","pa_farbe-amarillo","pa_farbe-naranja","pa_farbe-negro","pa_farbe-verde-bronce","first","instock","product-type-variable"],"acf":[],"yoast_head":"<title>cargo.case PE 19975.5852F | Maleta de carga B&amp;W en muchos tama\u00f1os - B&amp;W Cases of Success<\/title>\n<meta name=\"description\" content=\"Pr\u00e1ctico malet\u00edn multiusos B&amp;N \u2713A prueba de golpes \u2713A prueba de agua \u2713Con asa de transporte \u2713Cierre de seguridad \u2794 \u00a1Ases\u00f3rate ahora!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/cargo-case-hdpe-19975-5852f\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cargo.case PE 19975.5852F | Maleta de carga B&amp;W en muchos tama\u00f1os - B&amp;W Cases of Success\" \/>\n<meta property=\"og:description\" content=\"Pr\u00e1ctico malet\u00edn multiusos B&amp;N \u2713A prueba de golpes \u2713A prueba de agua \u2713Con asa de transporte \u2713Cierre de seguridad \u2794 \u00a1Ases\u00f3rate ahora!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/cargo-case-hdpe-19975-5852f\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T08:34:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-19975-5852F_closed-forklift_bw-international.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/cargo-case-hdpe-19975-5852f\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/cargo-case-hdpe-19975-5852f\\\/\",\"name\":\"cargo.case PE 19975.5852F | Maleta de carga B&amp;W en muchos tama\u00f1os - B&amp;W Cases of Success\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/cargo-case-hdpe-19975-5852f\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/cargo-case-hdpe-19975-5852f\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cargo-case_HDPE-19975-5852F_closed-forklift_bw-international.jpg\",\"datePublished\":\"2026-02-11T09:47:55+00:00\",\"dateModified\":\"2026-06-24T08:34:22+00:00\",\"description\":\"Pr\u00e1ctico malet\u00edn multiusos B&N \u2713A prueba de golpes \u2713A prueba de agua \u2713Con asa de transporte \u2713Cierre de seguridad \u2794 \u00a1Ases\u00f3rate ahora!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/cargo-case-hdpe-19975-5852f\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/cargo-case-hdpe-19975-5852f\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/cargo-case-hdpe-19975-5852f\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cargo-case_HDPE-19975-5852F_closed-forklift_bw-international.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cargo-case_HDPE-19975-5852F_closed-forklift_bw-international.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"Aberturas para carretillas elevadoras\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/cargo-case-hdpe-19975-5852f\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maletas de transporte y almacenamiento\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkte\\\/maletas-de-transporte-y-almacenamiento\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cargo case\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkte\\\/maletas-de-transporte-y-almacenamiento\\\/cargo-case\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"cargo.case PE 19975.5852F | Maleta de carga B&amp;W en muchos tama\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"cargo.case PE 19975.5852F | Maleta de carga B&amp;W en muchos tama\u00f1os - B&amp;W Cases of Success","description":"Pr\u00e1ctico malet\u00edn multiusos B&N \u2713A prueba de golpes \u2713A prueba de agua \u2713Con asa de transporte \u2713Cierre de seguridad \u2794 \u00a1Ases\u00f3rate ahora!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/cargo-case-hdpe-19975-5852f\/","og_locale":"es_ES","og_type":"article","og_title":"cargo.case PE 19975.5852F | Maleta de carga B&amp;W en muchos tama\u00f1os - B&amp;W Cases of Success","og_description":"Pr\u00e1ctico malet\u00edn multiusos B&N \u2713A prueba de golpes \u2713A prueba de agua \u2713Con asa de transporte \u2713Cierre de seguridad \u2794 \u00a1Ases\u00f3rate ahora!","og_url":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/cargo-case-hdpe-19975-5852f\/","og_site_name":"B&amp;W Cases of Success","article_modified_time":"2026-06-24T08:34:22+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-19975-5852F_closed-forklift_bw-international.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/cargo-case-hdpe-19975-5852f\/","url":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/cargo-case-hdpe-19975-5852f\/","name":"cargo.case PE 19975.5852F | Maleta de carga B&amp;W en muchos tama\u00f1os - B&amp;W Cases of Success","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/cargo-case-hdpe-19975-5852f\/#primaryimage"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/cargo-case-hdpe-19975-5852f\/#primaryimage"},"thumbnailUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-19975-5852F_closed-forklift_bw-international.jpg","datePublished":"2026-02-11T09:47:55+00:00","dateModified":"2026-06-24T08:34:22+00:00","description":"Pr\u00e1ctico malet\u00edn multiusos B&N \u2713A prueba de golpes \u2713A prueba de agua \u2713Con asa de transporte \u2713Cierre de seguridad \u2794 \u00a1Ases\u00f3rate ahora!","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/cargo-case-hdpe-19975-5852f\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/cargo-case-hdpe-19975-5852f\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/cargo-case-hdpe-19975-5852f\/#primaryimage","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-19975-5852F_closed-forklift_bw-international.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-19975-5852F_closed-forklift_bw-international.jpg","width":1920,"height":1920,"caption":"Aberturas para carretillas elevadoras"},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/cargo-case-hdpe-19975-5852f\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/www.b-w-cases-of-success.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Maletas de transporte y almacenamiento","item":"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-de-transporte-y-almacenamiento\/"},{"@type":"ListItem","position":4,"name":"Cargo case","item":"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-de-transporte-y-almacenamiento\/cargo-case\/"},{"@type":"ListItem","position":5,"name":"cargo.case PE 19975.5852F | Maleta de carga B&amp;W en muchos tama\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/es\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product\/25056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/media\/25063"}],"wp:attachment":[{"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/media?parent=25056"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product_brand?post=25056"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product_cat?post=25056"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product_tag?post=25056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}