{"id":25165,"date":"2026-02-12T08:47:46","date_gmt":"2026-02-12T07:47:46","guid":{"rendered":"httpsss:\/\/dev.b-w-cases-of-success.de\/?post_type=product&#038;p=25165"},"modified":"2026-06-24T11:42:44","modified_gmt":"2026-06-24T09:42:44","slug":"rack-case-hdpe-3u-480","status":"publish","type":"product","link":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/rack-case-hdpe-3u-480\/","title":{"rendered":"rack.case PE.3U.480 | Caja rack B&amp;W de 480 mm de carcasa"},"content":{"rendered":"<div>\n<ul>\n<li>Robusto armaz\u00f3n moldeado por rotaci\u00f3n de material PE resistente a los impactos<\/li>\n<li>Amortiguadores para una m\u00e1xima protecci\u00f3n durante el transporte<\/li>\n<li>Cubierta de 80 mm o 120 mm con rodillos de borde<\/li>\n<li>Ancho de rack est\u00e1ndar de 19 pulgadas seg\u00fan ANSI\/EIA-310-C<\/li>\n<li>Rieles con orificios cuadrados para tuercas enjauladas est\u00e1ndar de 6 mm<\/li>\n<li>Asas de pol\u00edmero de alta resistencia con empu\u00f1adura de goma blanda<\/li>\n<li>Fijaciones de acero inoxidable<\/li>\n<li>V\u00e1lvula mec\u00e1nica de alivio de presi\u00f3n (est\u00e1ndar)<\/li>\n<li>Junta estanca entre la carcasa y la tapa<\/li>\n<li>Colgador de tapa (est\u00e1ndar)<\/li>\n<li>Varias opciones de color<\/li>\n<li>Disponible en profundidades de rack de <strong>380 mm &#8211; 480 mm &#8211; 610 mm &#8211; 780 mm<\/strong><\/li>\n<li>Tama\u00f1os <strong>de 3U a 14U<\/strong><\/li>\n<li>Sistema de apilado y almacenamiento Multibrix\u00ae (apilado seguro y apilado cruzado de cajas del mismo o distinto tama\u00f1o).<\/li>\n<li>Las l\u00edneas de rejilla de la tapa est\u00e1n especialmente dise\u00f1adas para el flejado de palets<\/li>\n<li>Dise\u00f1o ligero y compacto<\/li>\n<li>Rango de carga \u00fatil est\u00e1ndar 20-75 kg<\/li>\n<li>Probado y aprobado &#8211; MIL-STD 810 G, STANAG 4280, Def Stan 81-41<\/li>\n<li>Certificado IP 65 para la entrada de polvo y agua<\/li>\n<\/ul>\n<p>Las maletas rack.case tambi\u00e9n est\u00e1n disponibles en otros colores bajo pedido.<br \/>\nPuedes encontrar un resumen completo de todos los tama\u00f1os y configuraciones disponibles en nuestra <a href=\"https:\/\/dev.b-w-cases-of-success.de\/es\/?attachment_id=24601\" target=\"_blank\" rel=\"noopener\"><strong>resumen de productos<\/strong><\/a>.<\/p>\n<\/div>\n<div style=\"display:flex; gap:10px;justify-content:center\" class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend\">\n\t\t<a  href=\"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product\/25165\/?action=genpdf&amp;id=25165\" class=\"pgfw-single-pdf-download-button\" target=_blank><img src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/icon-download.svg\" title=\"Generar PDF\" style=\"width:auto; height:45px;\"><\/a>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Robusto armaz\u00f3n moldeado por rotaci\u00f3n de material PE resistente a los impactos Amortiguadores para una m\u00e1xima protecci\u00f3n durante el transporte Cubierta de 80 mm o 120 mm con rodillos de borde Ancho de rack est\u00e1ndar de 19 pulgadas seg\u00fan ANSI\/EIA-310-C Rieles con orificios cuadrados para tuercas enjauladas est\u00e1ndar de 6 mm Asas de pol\u00edmero de [&hellip;]<\/p>\n","protected":false},"featured_media":25172,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[883,860],"product_tag":[],"class_list":["post-25165","product","type-product","status-publish","has-post-thumbnail","product_features-apilable","product_features-extremadamente-resistente","product_features-material-resistente","product_cat-rack","product_cat-maleta-rigida","pa_farbe-amarillo","pa_farbe-naranja","pa_farbe-negro","pa_farbe-verde-bronce","first","instock","product-type-variable"],"acf":[],"yoast_head":"<title>rack.case PE.3U.480 | Caja rack B&amp;W de 480 mm de carcasa - B&amp;W Cases of Success<\/title>\n<meta name=\"description\" content=\"Pr\u00e1ctico malet\u00edn multiusos B&amp;N \u2713A prueba de golpes \u2713A prueba de agua \u2713Con asa de transporte \u2713Cierre de seguridad \u2794 \u00a1Ases\u00f3rate ahora!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/rack-case-hdpe-3u-480\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"rack.case PE.3U.480 | Caja rack B&amp;W de 480 mm de carcasa - B&amp;W Cases of Success\" \/>\n<meta property=\"og:description\" content=\"Pr\u00e1ctico malet\u00edn multiusos B&amp;N \u2713A prueba de golpes \u2713A prueba de agua \u2713Con asa de transporte \u2713Cierre de seguridad \u2794 \u00a1Ases\u00f3rate ahora!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/rack-case-hdpe-3u-480\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T09:42:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/rack-case_HDPE-3U-480_closed_bw-international.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/rack-case-hdpe-3u-480\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/rack-case-hdpe-3u-480\\\/\",\"name\":\"rack.case PE.3U.480 | Caja rack B&amp;W de 480 mm de carcasa - B&amp;W Cases of Success\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/rack-case-hdpe-3u-480\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/rack-case-hdpe-3u-480\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/rack-case_HDPE-3U-480_closed_bw-international.jpg\",\"datePublished\":\"2026-02-12T07:47:46+00:00\",\"dateModified\":\"2026-06-24T09:42:44+00:00\",\"description\":\"Pr\u00e1ctico malet\u00edn multiusos B&N \u2713A prueba de golpes \u2713A prueba de agua \u2713Con asa de transporte \u2713Cierre de seguridad \u2794 \u00a1Ases\u00f3rate ahora!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/rack-case-hdpe-3u-480\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/rack-case-hdpe-3u-480\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/rack-case-hdpe-3u-480\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/rack-case_HDPE-3U-480_closed_bw-international.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/rack-case_HDPE-3U-480_closed_bw-international.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"con ruedas (W)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkt\\\/rack-case-hdpe-3u-480\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maletas de transporte y almacenamiento\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkte\\\/maletas-de-transporte-y-almacenamiento\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Rack cases\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkte\\\/maletas-de-transporte-y-almacenamiento\\\/maleta-rigida\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"rack.case PE.3U.480 | Caja rack B&amp;W de 480 mm de carcasa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"rack.case PE.3U.480 | Caja rack B&amp;W de 480 mm de carcasa - B&amp;W Cases of Success","description":"Pr\u00e1ctico malet\u00edn multiusos B&N \u2713A prueba de golpes \u2713A prueba de agua \u2713Con asa de transporte \u2713Cierre de seguridad \u2794 \u00a1Ases\u00f3rate ahora!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/rack-case-hdpe-3u-480\/","og_locale":"es_ES","og_type":"article","og_title":"rack.case PE.3U.480 | Caja rack B&amp;W de 480 mm de carcasa - B&amp;W Cases of Success","og_description":"Pr\u00e1ctico malet\u00edn multiusos B&N \u2713A prueba de golpes \u2713A prueba de agua \u2713Con asa de transporte \u2713Cierre de seguridad \u2794 \u00a1Ases\u00f3rate ahora!","og_url":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/rack-case-hdpe-3u-480\/","og_site_name":"B&amp;W Cases of Success","article_modified_time":"2026-06-24T09:42:44+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/rack-case_HDPE-3U-480_closed_bw-international.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/rack-case-hdpe-3u-480\/","url":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/rack-case-hdpe-3u-480\/","name":"rack.case PE.3U.480 | Caja rack B&amp;W de 480 mm de carcasa - B&amp;W Cases of Success","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/rack-case-hdpe-3u-480\/#primaryimage"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/rack-case-hdpe-3u-480\/#primaryimage"},"thumbnailUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/rack-case_HDPE-3U-480_closed_bw-international.jpg","datePublished":"2026-02-12T07:47:46+00:00","dateModified":"2026-06-24T09:42:44+00:00","description":"Pr\u00e1ctico malet\u00edn multiusos B&N \u2713A prueba de golpes \u2713A prueba de agua \u2713Con asa de transporte \u2713Cierre de seguridad \u2794 \u00a1Ases\u00f3rate ahora!","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/rack-case-hdpe-3u-480\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/rack-case-hdpe-3u-480\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/rack-case-hdpe-3u-480\/#primaryimage","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/rack-case_HDPE-3U-480_closed_bw-international.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/rack-case_HDPE-3U-480_closed_bw-international.jpg","width":1920,"height":1920,"caption":"con ruedas (W)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkt\/rack-case-hdpe-3u-480\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/www.b-w-cases-of-success.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Maletas de transporte y almacenamiento","item":"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-de-transporte-y-almacenamiento\/"},{"@type":"ListItem","position":4,"name":"Rack cases","item":"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-de-transporte-y-almacenamiento\/maleta-rigida\/"},{"@type":"ListItem","position":5,"name":"rack.case PE.3U.480 | Caja rack B&amp;W de 480 mm de carcasa"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/es\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product\/25165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/media\/25172"}],"wp:attachment":[{"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/media?parent=25165"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product_brand?post=25165"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product_cat?post=25165"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product_tag?post=25165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}