{"id":416,"count":2,"description":"","link":"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-multiusos\/primeros-auxilios\/","name":"Primeros auxilios","slug":"primeros-auxilios","taxonomy":"product_cat","parent":182,"meta":[],"menu_order":14,"acf":[],"yoast_head":"<title>Erste-Hilfe-Koffer von B&amp;W | F\u00fcr Betriebe &amp; Teams<\/title>\n<meta name=\"description\" content=\"Robuste Erste-Hilfe-Koffer von B&amp;W: \u2713schlagfest &amp; wasserdicht \u2713gef\u00fcllt nach DIN 13169 \u2713ideal f\u00fcr Betrieb &amp; Baustelle \u2713praktisch \u2794 Jetzt informieren!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-multiusos\/primeros-auxilios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erste-Hilfe-Koffer von B&amp;W | F\u00fcr Betriebe &amp; Teams\" \/>\n<meta property=\"og:description\" content=\"Robuste Erste-Hilfe-Koffer von B&amp;W: \u2713schlagfest &amp; wasserdicht \u2713gef\u00fcllt nach DIN 13169 \u2713ideal f\u00fcr Betrieb &amp; Baustelle \u2713praktisch \u2794 Jetzt informieren!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-multiusos\/primeros-auxilios\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1067\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkte\\\/maletas-multiusos\\\/primeros-auxilios\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkte\\\/maletas-multiusos\\\/primeros-auxilios\\\/\",\"name\":\"Erste-Hilfe-Koffer von B&W | F\u00fcr Betriebe & Teams\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#website\"},\"description\":\"Robuste Erste-Hilfe-Koffer von B&W: \u2713schlagfest & wasserdicht \u2713gef\u00fcllt nach DIN 13169 \u2713ideal f\u00fcr Betrieb & Baustelle \u2713praktisch \u2794 Jetzt informieren!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkte\\\/maletas-multiusos\\\/primeros-auxilios\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkte\\\/maletas-multiusos\\\/primeros-auxilios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maletas multiusos\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/produkte\\\/maletas-multiusos\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Primeros auxilios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"Erste-Hilfe-Koffer von B&W | F\u00fcr Betriebe & Teams","description":"Robuste Erste-Hilfe-Koffer von B&W: \u2713schlagfest & wasserdicht \u2713gef\u00fcllt nach DIN 13169 \u2713ideal f\u00fcr Betrieb & Baustelle \u2713praktisch \u2794 Jetzt informieren!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-multiusos\/primeros-auxilios\/","og_locale":"es_ES","og_type":"article","og_title":"Erste-Hilfe-Koffer von B&W | F\u00fcr Betriebe & Teams","og_description":"Robuste Erste-Hilfe-Koffer von B&W: \u2713schlagfest & wasserdicht \u2713gef\u00fcllt nach DIN 13169 \u2713ideal f\u00fcr Betrieb & Baustelle \u2713praktisch \u2794 Jetzt informieren!","og_url":"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-multiusos\/primeros-auxilios\/","og_site_name":"B&amp;W Cases of Success","og_image":[{"width":1067,"height":1067,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-multiusos\/primeros-auxilios\/","url":"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-multiusos\/primeros-auxilios\/","name":"Erste-Hilfe-Koffer von B&W | F\u00fcr Betriebe & Teams","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#website"},"description":"Robuste Erste-Hilfe-Koffer von B&W: \u2713schlagfest & wasserdicht \u2713gef\u00fcllt nach DIN 13169 \u2713ideal f\u00fcr Betrieb & Baustelle \u2713praktisch \u2794 Jetzt informieren!","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-multiusos\/primeros-auxilios\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-multiusos\/primeros-auxilios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/www.b-w-cases-of-success.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Maletas multiusos","item":"https:\/\/www.b-w-cases-of-success.com\/es\/produkte\/maletas-multiusos\/"},{"@type":"ListItem","position":4,"name":"Primeros auxilios"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/es\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product_cat\/416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product_cat\/182"}],"wp:post_type":[{"href":"https:\/\/www.b-w-cases-of-success.com\/es\/wp-json\/wp\/v2\/product?product_cat=416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}