{"id":17599,"date":"2025-01-27T09:04:26","date_gmt":"2025-01-27T08:04:26","guid":{"rendered":""},"modified":"2026-08-28T08:41:42","modified_gmt":"2026-08-28T06:41:42","slug":"international","status":"publish","type":"page","link":"https:\/\/www.b-w-cases-of-success.com\/fr\/contact\/international\/","title":{"rendered":"International"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"17599\" class=\"elementor elementor-17599 elementor-852\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b758cf6 e-con-full e-flex e-con e-parent\" data-id=\"b758cf6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e927afe elementor-widget__width-inherit elementor-widget elementor-widget-ucaddon_title_hero_custom\" data-id=\"e927afe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_title_hero_custom.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Title Hero Custom -->\n<style>\/* widget: Title Hero Custom *\/\n\n#uc_title_hero_custom_elementor_e927afe *{\n\tbox-sizing: border-box;\n}\n#uc_title_hero_custom_elementor_e927afe{\n\tposition:relative;\n\toverflow:hidden;\n    display:flex;\n    justify-content:flex-end;\n  \talign-items:center;\n    flex-direction: column;\n    background-blend-mode: normal;\n}\n\n#uc_title_hero_custom_elementor_e927afe .ue_title_hero_container{\n\n    text-align:center;\n    position:relative;\n    z-index:1;\n}\n#uc_title_hero_custom_elementor_e927afe .ue_title{\n\n\tdisplay:inline-block;\n}\n\n#uc_title_hero_custom_elementor_e927afe a{\n    display: inline-block;\n\ttext-decoration:none;\n}\n\n#uc_title_hero_custom_elementor_e927afe .ue_title_hero_overlay\n{\n  position:absolute;\n  top:0;\n  bottom:0;\n  left:0;\n  right:0;\n}\n\n.ue_title\n{\n  font-size:52px;\n}\n\n<\/style>\n\n<div class=\"ue_title_hero\" id=\"uc_title_hero_custom_elementor_e927afe\">\n    <div class=\"ue_title_hero_overlay\"><\/div>\n    <div class=\"ue_title_hero_container\">\n      \t    \t<h1 class=\"ue_title\">Contacts internationaux<\/h1>\n        <div><\/div>\n              \n        \t\n      \n            <\/div>\n<\/div>\n<!-- end Title Hero Custom -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-790d0e1 e-con-full e-flex e-con e-child\" data-id=\"790d0e1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd038b3 e-flex e-con-boxed e-con e-parent\" data-id=\"fd038b3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c650bb7 elementor-align-left elementor-widget__width-inherit elementor-widget elementor-widget-global elementor-global-983 elementor-widget-breadcrumbs\" data-id=\"c650bb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.b-w-cases-of-success.com\/fr\/page-daccueil\/\">Home<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ffae241 e-flex e-con-boxed e-con e-parent\" data-id=\"ffae241\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3802d18 elementor-widget elementor-widget-ucaddon_titel_text_custom\" data-id=\"3802d18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_titel_text_custom.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Custom Titel Text Button -->\n<style>\/* widget: Custom Titel Text Button *\/\n\n.uc_titel_text_custom_elementor_3802d18.container-titel-text .titel-container{\n  text-align: center;\n}\n\n.uc_titel_text_custom_elementor_3802d18.container-titel-text .text-container{\n  text-align: center;\n}\n\n.uc_titel_text_custom_elementor_3802d18.container-titel-text{\n\tdisplay:flex;\n  \tflex-direction:column;\n}\n\n<\/style>\n\n<div class=\"uc_titel_text_custom_elementor_3802d18 container-titel-text\">\n      <div class=\"titel-container\">\n     \n        <h1><\/h1>  \n        <\/div>\n        <div class=\"text-container\">    \n       \n          <p class=\"\" data-start=\"185\" data-end=\"414\"><strong data-start=\"185\" data-end=\"250\">Nos interlocuteurs internationaux sont \u00e0 votre service dans le monde entier.<\/strong><br data-start=\"250\" data-end=\"253\" \/>Quel que soit l'endroit du monde o\u00f9 vous souhaitez utiliser nos produits, nous sommes \u00e0 vos c\u00f4t\u00e9s gr\u00e2ce \u00e0 un solide r\u00e9seau d'interlocuteurs internationaux.<\/p><p class=\"\" data-start=\"416\" data-end=\"682\">Que vous ayez besoin de d\u00e9tails techniques, que vous recherchiez les accessoires ad\u00e9quats ou que vous souhaitiez obtenir des conseils personnalis\u00e9s : Nos experts locaux comprennent vos exigences - culturelles et techniques - et vous accompagnent personnellement vers la meilleure solution.<\/p><p class=\"\" data-start=\"684\" data-end=\"742\"><strong data-start=\"684\" data-end=\"742\">N'h\u00e9sitez pas \u00e0 nous contacter - nous serons ravis de r\u00e9pondre \u00e0 votre demande.<\/strong><\/p>\n           <\/div>\n    \n  <\/div>\n<!-- end Custom Titel Text Button -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-41c68e2 e-flex e-con-boxed e-con e-parent\" data-id=\"41c68e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da90d37 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"da90d37\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:17651,&quot;columns&quot;:3,&quot;_skin&quot;:&quot;post&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-17651\">.elementor-17651 .elementor-element.elementor-element-589ac91{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;}.elementor-17651 .elementor-element.elementor-element-817681c{--display:flex;--gap:30px 0px;--row-gap:30px;--column-gap:0px;--border-radius:30px 30px 30px 0px;--margin-top:20px;--margin-bottom:0px;--margin-left:0px;--margin-right:0px;--padding-top:25px;--padding-bottom:25px;--padding-left:25px;--padding-right:25px;}.elementor-17651 .elementor-element.elementor-element-817681c:not(.elementor-motion-effects-element-type-background), .elementor-17651 .elementor-element.elementor-element-817681c > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#F2F2F2;}.elementor-widget-text-editor{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );color:var( --e-global-color-text );}.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:var( --e-global-color-primary );}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap, .elementor-widget-text-editor.elementor-drop-cap-view-default .elementor-drop-cap{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-17651 .elementor-element.elementor-element-596f3cf{text-align:center;font-family:\"Neuropol X\", Sans-serif;font-size:20px;font-weight:400;color:var( --e-global-color-34e4459 );}.elementor-widget-theme-post-featured-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );}.elementor-17651 .elementor-element.elementor-element-9e54e1c{text-align:center;}.elementor-17651 .elementor-element.elementor-element-9e54e1c img{border-radius:20px 20px 20px 0px;}.elementor-17651 .elementor-element.elementor-element-274224b{--display:flex;--justify-content:center;--gap:30px 0px;--row-gap:30px;--column-gap:0px;--border-radius:30px 30px 30px 0px;}.elementor-17651 .elementor-element.elementor-element-274224b:not(.elementor-motion-effects-element-type-background), .elementor-17651 .elementor-element.elementor-element-274224b > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:var( --e-global-color-36fbfef );}.elementor-widget-theme-post-title .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );text-transform:var( --e-global-typography-primary-text-transform );color:var( --e-global-color-primary );}.elementor-17651 .elementor-element.elementor-element-3fd277e{text-align:center;}.elementor-17651 .elementor-element.elementor-element-3fd277e .elementor-heading-title{font-family:\"DIN2014\", Sans-serif;font-size:22px;font-weight:700;text-transform:uppercase;color:var( --e-global-color-66d6a4b );}.elementor-widget-heading .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );text-transform:var( --e-global-typography-primary-text-transform );color:var( --e-global-color-primary );}.elementor-17651 .elementor-element.elementor-element-bfc920e{text-align:center;}.elementor-17651 .elementor-element.elementor-element-bfc920e .elementor-heading-title{font-family:\"DIN2014\", Sans-serif;font-size:16px;font-weight:700;text-transform:uppercase;color:var( --e-global-color-66d6a4b );}.elementor-17651 .elementor-element.elementor-element-b37da60{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:center;--gap:12px 0px;--row-gap:12px;--column-gap:0px;}.elementor-widget-button .elementor-button{font-family:var( --e-global-typography-accent-font-family ), Sans-serif;font-weight:var( --e-global-typography-accent-font-weight );background-color:var( --e-global-color-accent );}.elementor-17651 .elementor-element.elementor-element-edc0277 .elementor-button-content-wrapper{flex-direction:row;}.elementor-17651 .elementor-element.elementor-element-edc0277 .elementor-button .elementor-button-content-wrapper{gap:10px;}.elementor-17651 .elementor-element.elementor-element-edc0277 .elementor-button{font-family:\"DIN2014\", Sans-serif;font-size:18px;font-weight:400;text-decoration:underline;fill:var( --e-global-color-66d6a4b );color:var( --e-global-color-66d6a4b );background-color:var( --e-global-color-36fbfef );border-style:none;padding:0px 0px 0px 0px;}.elementor-17651 .elementor-element.elementor-element-edc0277 .elementor-button:hover, .elementor-17651 .elementor-element.elementor-element-edc0277 .elementor-button:focus{background-color:var( --e-global-color-36fbfef );border-color:var( --e-global-color-36fbfef );}.elementor-17651 .elementor-element.elementor-element-edc0277 > .elementor-widget-container{margin:0px 15px 0px 15px;}.elementor-17651 .elementor-element.elementor-element-6d7a096 .elementor-button-content-wrapper{flex-direction:row;}.elementor-17651 .elementor-element.elementor-element-6d7a096 .elementor-button .elementor-button-content-wrapper{gap:10px;}.elementor-17651 .elementor-element.elementor-element-6d7a096 .elementor-button{font-family:\"DIN2014\", Sans-serif;font-size:18px;font-weight:400;text-decoration:underline;fill:var( --e-global-color-66d6a4b );color:var( --e-global-color-66d6a4b );background-color:var( --e-global-color-36fbfef );border-style:none;padding:0px 0px 0px 0px;}.elementor-17651 .elementor-element.elementor-element-6d7a096 .elementor-button:hover, .elementor-17651 .elementor-element.elementor-element-6d7a096 .elementor-button:focus{background-color:var( --e-global-color-36fbfef );border-color:var( --e-global-color-36fbfef );}.elementor-17651 .elementor-element.elementor-element-6d7a096 > .elementor-widget-container{margin:0px 15px 0px 15px;}.elementor-17651 .elementor-element.elementor-element-3596914 .elementor-button-content-wrapper{flex-direction:row;}.elementor-17651 .elementor-element.elementor-element-3596914 .elementor-button .elementor-button-content-wrapper{gap:10px;}.elementor-17651 .elementor-element.elementor-element-3596914 .elementor-button{font-family:\"DIN2014\", Sans-serif;font-size:18px;font-weight:400;text-decoration:underline;fill:var( --e-global-color-66d6a4b );color:var( --e-global-color-66d6a4b );background-color:var( --e-global-color-36fbfef );border-style:none;padding:0px 0px 0px 0px;}.elementor-17651 .elementor-element.elementor-element-3596914 .elementor-button:hover, .elementor-17651 .elementor-element.elementor-element-3596914 .elementor-button:focus{background-color:var( --e-global-color-36fbfef );border-color:var( --e-global-color-36fbfef );}.elementor-17651 .elementor-element.elementor-element-3596914 > .elementor-widget-container{margin:0px 15px 0px 15px;}.elementor-17651 .elementor-element.elementor-element-a25cae3 .elementor-button-content-wrapper{flex-direction:row;}.elementor-17651 .elementor-element.elementor-element-a25cae3 .elementor-button .elementor-button-content-wrapper{gap:10px;}.elementor-17651 .elementor-element.elementor-element-a25cae3 .elementor-button{font-family:\"DIN2014\", Sans-serif;font-size:18px;font-weight:400;text-decoration:underline;fill:var( --e-global-color-66d6a4b );color:var( --e-global-color-66d6a4b );background-color:var( --e-global-color-36fbfef );border-style:none;padding:0px 0px 0px 0px;}.elementor-17651 .elementor-element.elementor-element-a25cae3 .elementor-button:hover, .elementor-17651 .elementor-element.elementor-element-a25cae3 .elementor-button:focus{background-color:var( --e-global-color-36fbfef );border-color:var( --e-global-color-36fbfef );}.elementor-17651 .elementor-element.elementor-element-a25cae3 > .elementor-widget-container{margin:0px 15px 0px 15px;}.elementor-17651 .elementor-element.elementor-element-548b738 .elementor-button-content-wrapper{flex-direction:row;}.elementor-17651 .elementor-element.elementor-element-548b738 .elementor-button .elementor-button-content-wrapper{gap:10px;}.elementor-17651 .elementor-element.elementor-element-548b738 .elementor-button{font-family:\"DIN2014\", Sans-serif;font-size:18px;font-weight:400;text-decoration:underline;fill:var( --e-global-color-66d6a4b );color:var( --e-global-color-66d6a4b );background-color:var( --e-global-color-36fbfef );border-style:none;padding:0px 0px 0px 0px;}.elementor-17651 .elementor-element.elementor-element-548b738 .elementor-button:hover, .elementor-17651 .elementor-element.elementor-element-548b738 .elementor-button:focus{background-color:var( --e-global-color-36fbfef );border-color:var( --e-global-color-36fbfef );}.elementor-17651 .elementor-element.elementor-element-548b738 > .elementor-widget-container{margin:0px 15px 0px 15px;}@media(max-width:1024px){.elementor-17651 .elementor-element.elementor-element-274224b{--flex-wrap:wrap;}.elementor-17651 .elementor-element.elementor-element-b37da60{--flex-wrap:wrap;}.elementor-17651 .elementor-element.elementor-element-edc0277 > .elementor-widget-container{margin:0px 15px 0px 15px;}.elementor-17651 .elementor-element.elementor-element-6d7a096 > .elementor-widget-container{margin:0px 15px 0px 15px;}.elementor-17651 .elementor-element.elementor-element-3596914 > .elementor-widget-container{margin:0px 15px 0px 15px;}.elementor-17651 .elementor-element.elementor-element-a25cae3 > .elementor-widget-container{margin:0px 15px 0px 15px;}.elementor-17651 .elementor-element.elementor-element-548b738 > .elementor-widget-container{margin:0px 15px 0px 15px;}}\/* Start custom CSS for theme-post-title, class: .elementor-element-3fd277e *\/.elementor-17651 .elementor-element.elementor-element-3fd277e{\n    display: initial;\n}\/* End custom CSS *\/\n\/* Start custom CSS for button, class: .elementor-element-edc0277 *\/.elementor-17651 .elementor-element.elementor-element-edc0277 .elementor-button-icon svg{\n    width: 24px;\n    height: 24px;\n}\n\n.elementor-button-content-wrapper {\n    display: flex;\n    align-items: center;\n}\/* End custom CSS *\/\n\/* Start custom CSS for button, class: .elementor-element-6d7a096 *\/.elementor-17651 .elementor-element.elementor-element-6d7a096 .elementor-button-icon svg{\n    width: 24px;\n    height: 24px;\n}\n\n.elementor-button-content-wrapper {\n    display: flex;\n    align-items: center;\n}\/* End custom CSS *\/\n\/* Start custom CSS for button, class: .elementor-element-3596914 *\/.elementor-17651 .elementor-element.elementor-element-3596914 .elementor-button-icon svg{\n    width: 24px;\n    height: 24px;\n}\n\n.elementor-button-content-wrapper {\n    display: flex;\n    align-items: center;\n}\/* End custom CSS *\/\n\/* Start custom CSS for button, class: .elementor-element-a25cae3 *\/.elementor-17651 .elementor-element.elementor-element-a25cae3 .elementor-button-icon svg{\n    width: 24px;\n    height: 24px;\n}\n\n.elementor-button-content-wrapper {\n    display: flex;\n    align-items: center;\n}\/* End custom CSS *\/\n\/* Start custom CSS for button, class: .elementor-element-548b738 *\/.elementor-17651 .elementor-element.elementor-element-548b738 .elementor-button-icon svg{\n    width: 24px;\n    height: 24px;\n}\n\n.elementor-button-content-wrapper {\n    display: flex;\n    align-items: center;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"17651\" class=\"elementor elementor-17651 elementor-2696 elementor-2696 e-loop-item e-loop-item-17874 post-17874 team type-team status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-589ac91 e-con-full e-flex e-con e-parent\" data-id=\"589ac91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-817681c e-con-full e-flex e-con e-child\" data-id=\"817681c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-596f3cf elementor-widget elementor-widget-text-editor\" data-id=\"596f3cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAm\u00e9rique du Nord\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e54e1c elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9e54e1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profilbild-chris-temple-2024-bw-international_website.jpg\" class=\"attachment-full size-full wp-image-5341\" alt=\"Chris Temple sourit, les bras crois\u00e9s. Il est directeur des ventes chez B&amp;W International, responsable de l&apos;Am\u00e9rique du Nord.\" srcset=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profilbild-chris-temple-2024-bw-international_website.jpg 500w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profilbild-chris-temple-2024-bw-international_website-300x300.jpg 300w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profilbild-chris-temple-2024-bw-international_website-100x100.jpg 100w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profilbild-chris-temple-2024-bw-international_website-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-274224b e-con-full e-flex e-con e-child\" data-id=\"274224b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd277e elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"3fd277e\" data-element_type=\"widget\" data-e-type=\"widget\" chris=\"\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Chris Temple<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfc920e elementor-widget elementor-widget-heading\" data-id=\"bfc920e\" data-element_type=\"widget\" data-e-type=\"widget\" directeur=\"\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Directeur des ventes<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b37da60 e-con-full e-flex e-con e-child\" data-id=\"b37da60\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-edc0277 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"edc0277\" data-element_type=\"widget\" data-e-type=\"widget\" chris=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:chris.temple@b-w-international.com\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"mail\"><mask id=\"mask0_31_3785\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"25\"><rect id=\"Bounding box\" y=\"0.5\" width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_31_3785)\"><path id=\"mail_2\" d=\"M2.5 20V5H21.5V20H2.5ZM12 13.0577L4 7.94225V18.5H20V7.94225L12 13.0577ZM12 11.5L19.8463 6.5H4.15375L12 11.5ZM4 7.94225V6.5V18.5V7.94225Z\" fill=\"#009FDF\"><\/path><\/g><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">E-mail<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d7a096 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6d7a096\" data-element_type=\"widget\" data-e-type=\"widget\" tel=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:+17347445566\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"call\"><mask id=\"mask0_31_3775\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"25\"><rect id=\"Bounding box\" y=\"0.5\" width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_31_3775)\"><path id=\"call_2\" d=\"M19.575 21C17.6327 21 15.6983 20.5676 13.772 19.7028C11.8458 18.8381 10.0847 17.6077 8.4885 16.0115C6.89883 14.4153 5.67 12.6535 4.802 10.726C3.934 8.7985 3.5 6.86483 3.5 4.925V4H8.66925L9.55575 8.55375L6.78275 11.2462C7.19425 11.9667 7.63458 12.6363 8.10375 13.2548C8.57308 13.8734 9.06925 14.4392 9.59225 14.952C10.1013 15.4738 10.6673 15.9668 11.2905 16.4308C11.9135 16.8949 12.6064 17.3411 13.3693 17.7693L16.125 14.9655L20.5 15.8558V21H19.575ZM6.073 9.827L7.94425 8.04225L7.44225 5.5H5.0155C5.06667 6.25633 5.18042 6.99258 5.35675 7.70875C5.53308 8.42475 5.77183 9.13083 6.073 9.827ZM14.773 18.4693C15.414 18.7654 16.0977 18.9984 16.824 19.1683C17.5503 19.3381 18.2757 19.4384 19 19.4693V17.0673L16.6307 16.5922L14.773 18.4693Z\" fill=\"#009FDF\"><\/path><\/g><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">+1 734 744 5566<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a25cae3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a25cae3\" data-element_type=\"widget\" data-e-type=\"widget\" chris=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.linkedin.com\/in\/christopher-robert-temple\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"icon-linkedin\" clip-path=\"url(#clip0_31_3795)\"><path id=\"Vector\" d=\"M24 3.83333C24 3.79333 24 3.76 24 3.72C23.9706 2.85574 23.6065 2.03672 22.9845 1.43591C22.3625 0.835091 21.5314 0.499501 20.6667 0.500001H3.33333C2.44928 0.500001 1.60143 0.85119 0.976311 1.47631C0.35119 2.10143 5.57857e-07 2.94928 5.57857e-07 3.83333V21.1667C-0.000499416 22.0314 0.335091 22.8625 0.935907 23.4845C1.53672 24.1065 2.35574 24.4706 3.22 24.5H3.33333H20.6667H20.8067C21.6426 24.4656 22.4349 24.1181 23.0265 23.5265C23.6181 22.9349 23.9656 22.1426 24 21.3067C24 21.26 24 21.2133 24 21.1667V3.83333ZM22 21.1667C22 21.5203 21.8595 21.8594 21.6095 22.1095C21.3594 22.3595 21.0203 22.5 20.6667 22.5H3.33333C2.97971 22.5 2.64057 22.3595 2.39052 22.1095C2.14048 21.8594 2 21.5203 2 21.1667V3.83333C2 3.47971 2.14048 3.14057 2.39052 2.89052C2.64057 2.64048 2.97971 2.5 3.33333 2.5H20.6667C21.0203 2.5 21.3594 2.64048 21.6095 2.89052C21.8595 3.14057 22 3.47971 22 3.83333V21.1667Z\" fill=\"#009FDF\"><\/path><path id=\"Vector_2\" d=\"M8.29309 6.75977H5.91309V8.95977H8.29309V6.75977Z\" fill=\"#009FDF\"><\/path><path id=\"Vector_3\" d=\"M8.29309 10.1797H5.91309V19.1664H8.29309V10.1797Z\" fill=\"#009FDF\"><\/path><path id=\"Vector_4\" d=\"M18.307 10.9797C18.0488 10.6611 17.7139 10.4134 17.3337 10.2597C16.8794 10.0632 16.3886 9.96553 15.8937 9.97306C15.3136 9.9692 14.7413 10.1061 14.2258 10.372C13.7102 10.6379 13.2669 11.0249 12.9337 11.4997V10.1664H10.707V19.1664H13.087V15.0931C13.0551 14.4014 13.1156 13.7087 13.267 13.0331C13.3844 12.668 13.6187 12.3517 13.9337 12.1331C14.2605 11.9068 14.6496 11.788 15.047 11.7931C15.3388 11.7848 15.6258 11.8687 15.867 12.0331C16.1006 12.1962 16.2759 12.4298 16.367 12.6997C16.5013 13.3191 16.5528 13.9535 16.5204 14.5864V19.1664H18.8937V13.5797C18.9085 13.0434 18.866 12.507 18.767 11.9797C18.6849 11.618 18.5282 11.2774 18.307 10.9797Z\" fill=\"#009FDF\"><\/path><\/g><defs><clipPath id=\"clip0_31_3795\"><rect width=\"24\" height=\"24\" fill=\"white\" transform=\"translate(0 0.5)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Linkedin<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"17651\" class=\"elementor elementor-17651 elementor-2696 elementor-2696 e-loop-item e-loop-item-17871 post-17871 team type-team status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-589ac91 e-con-full e-flex e-con e-parent\" data-id=\"589ac91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-817681c e-con-full e-flex e-con e-child\" data-id=\"817681c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-596f3cf elementor-widget elementor-widget-text-editor\" data-id=\"596f3cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tInde\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e54e1c elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9e54e1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profile-picture-rajeev-kushik-2025-bw-international_website.jpg\" class=\"attachment-full size-full wp-image-5349\" alt=\"Portrait de Rajeev Kaushik, directeur commercial de B&amp;W International pour l&apos;Inde, portant des lunettes et les bras crois\u00e9s sur un fond clair.\" srcset=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profile-picture-rajeev-kushik-2025-bw-international_website.jpg 500w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profile-picture-rajeev-kushik-2025-bw-international_website-300x300.jpg 300w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profile-picture-rajeev-kushik-2025-bw-international_website-100x100.jpg 100w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profile-picture-rajeev-kushik-2025-bw-international_website-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-274224b e-con-full e-flex e-con e-child\" data-id=\"274224b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd277e elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"3fd277e\" data-element_type=\"widget\" data-e-type=\"widget\" rajeev=\"\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Rajeev Kaushik<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfc920e elementor-widget elementor-widget-heading\" data-id=\"bfc920e\" data-element_type=\"widget\" data-e-type=\"widget\" directeur=\"\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Directeur des ventes<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b37da60 e-con-full e-flex e-con e-child\" data-id=\"b37da60\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-edc0277 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"edc0277\" data-element_type=\"widget\" data-e-type=\"widget\" rajeev=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:rajeev.kaushik@b-w-international.com\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"mail\"><mask id=\"mask0_31_3785\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"25\"><rect id=\"Bounding box\" y=\"0.5\" width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_31_3785)\"><path id=\"mail_2\" d=\"M2.5 20V5H21.5V20H2.5ZM12 13.0577L4 7.94225V18.5H20V7.94225L12 13.0577ZM12 11.5L19.8463 6.5H4.15375L12 11.5ZM4 7.94225V6.5V18.5V7.94225Z\" fill=\"#009FDF\"><\/path><\/g><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">E-mail<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d7a096 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6d7a096\" data-element_type=\"widget\" data-e-type=\"widget\" tel=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:+919891114005\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"call\"><mask id=\"mask0_31_3775\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"25\"><rect id=\"Bounding box\" y=\"0.5\" width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_31_3775)\"><path id=\"call_2\" d=\"M19.575 21C17.6327 21 15.6983 20.5676 13.772 19.7028C11.8458 18.8381 10.0847 17.6077 8.4885 16.0115C6.89883 14.4153 5.67 12.6535 4.802 10.726C3.934 8.7985 3.5 6.86483 3.5 4.925V4H8.66925L9.55575 8.55375L6.78275 11.2462C7.19425 11.9667 7.63458 12.6363 8.10375 13.2548C8.57308 13.8734 9.06925 14.4392 9.59225 14.952C10.1013 15.4738 10.6673 15.9668 11.2905 16.4308C11.9135 16.8949 12.6064 17.3411 13.3693 17.7693L16.125 14.9655L20.5 15.8558V21H19.575ZM6.073 9.827L7.94425 8.04225L7.44225 5.5H5.0155C5.06667 6.25633 5.18042 6.99258 5.35675 7.70875C5.53308 8.42475 5.77183 9.13083 6.073 9.827ZM14.773 18.4693C15.414 18.7654 16.0977 18.9984 16.824 19.1683C17.5503 19.3381 18.2757 19.4384 19 19.4693V17.0673L16.6307 16.5922L14.773 18.4693Z\" fill=\"#009FDF\"><\/path><\/g><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">+91 989 11 14 00 5<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a25cae3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a25cae3\" data-element_type=\"widget\" data-e-type=\"widget\" rajeev=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.linkedin.com\/in\/rajeev-kaushik-bwi\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"icon-linkedin\" clip-path=\"url(#clip0_31_3795)\"><path id=\"Vector\" d=\"M24 3.83333C24 3.79333 24 3.76 24 3.72C23.9706 2.85574 23.6065 2.03672 22.9845 1.43591C22.3625 0.835091 21.5314 0.499501 20.6667 0.500001H3.33333C2.44928 0.500001 1.60143 0.85119 0.976311 1.47631C0.35119 2.10143 5.57857e-07 2.94928 5.57857e-07 3.83333V21.1667C-0.000499416 22.0314 0.335091 22.8625 0.935907 23.4845C1.53672 24.1065 2.35574 24.4706 3.22 24.5H3.33333H20.6667H20.8067C21.6426 24.4656 22.4349 24.1181 23.0265 23.5265C23.6181 22.9349 23.9656 22.1426 24 21.3067C24 21.26 24 21.2133 24 21.1667V3.83333ZM22 21.1667C22 21.5203 21.8595 21.8594 21.6095 22.1095C21.3594 22.3595 21.0203 22.5 20.6667 22.5H3.33333C2.97971 22.5 2.64057 22.3595 2.39052 22.1095C2.14048 21.8594 2 21.5203 2 21.1667V3.83333C2 3.47971 2.14048 3.14057 2.39052 2.89052C2.64057 2.64048 2.97971 2.5 3.33333 2.5H20.6667C21.0203 2.5 21.3594 2.64048 21.6095 2.89052C21.8595 3.14057 22 3.47971 22 3.83333V21.1667Z\" fill=\"#009FDF\"><\/path><path id=\"Vector_2\" d=\"M8.29309 6.75977H5.91309V8.95977H8.29309V6.75977Z\" fill=\"#009FDF\"><\/path><path id=\"Vector_3\" d=\"M8.29309 10.1797H5.91309V19.1664H8.29309V10.1797Z\" fill=\"#009FDF\"><\/path><path id=\"Vector_4\" d=\"M18.307 10.9797C18.0488 10.6611 17.7139 10.4134 17.3337 10.2597C16.8794 10.0632 16.3886 9.96553 15.8937 9.97306C15.3136 9.9692 14.7413 10.1061 14.2258 10.372C13.7102 10.6379 13.2669 11.0249 12.9337 11.4997V10.1664H10.707V19.1664H13.087V15.0931C13.0551 14.4014 13.1156 13.7087 13.267 13.0331C13.3844 12.668 13.6187 12.3517 13.9337 12.1331C14.2605 11.9068 14.6496 11.788 15.047 11.7931C15.3388 11.7848 15.6258 11.8687 15.867 12.0331C16.1006 12.1962 16.2759 12.4298 16.367 12.6997C16.5013 13.3191 16.5528 13.9535 16.5204 14.5864V19.1664H18.8937V13.5797C18.9085 13.0434 18.866 12.507 18.767 11.9797C18.6849 11.618 18.5282 11.2774 18.307 10.9797Z\" fill=\"#009FDF\"><\/path><\/g><defs><clipPath id=\"clip0_31_3795\"><rect width=\"24\" height=\"24\" fill=\"white\" transform=\"translate(0 0.5)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Linkedin<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"17651\" class=\"elementor elementor-17651 elementor-2696 elementor-2696 e-loop-item e-loop-item-17707 post-17707 team type-team status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-589ac91 e-con-full e-flex e-con e-parent\" data-id=\"589ac91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-817681c e-con-full e-flex e-con e-child\" data-id=\"817681c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-596f3cf elementor-widget elementor-widget-text-editor\" data-id=\"596f3cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAfrique et Moyen-Orient\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e54e1c elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9e54e1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profilbild-pascal-loyacono-2024-bw-international_website.jpg\" class=\"attachment-full size-full wp-image-5345\" alt=\"Portrait de Pascal Loyacono, directeur commercial de B&amp;W International pour l&apos;Afrique et le Moyen-Orient, en costume et lunettes.\" srcset=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profilbild-pascal-loyacono-2024-bw-international_website.jpg 500w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profilbild-pascal-loyacono-2024-bw-international_website-300x300.jpg 300w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profilbild-pascal-loyacono-2024-bw-international_website-100x100.jpg 100w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/profilbild-pascal-loyacono-2024-bw-international_website-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-274224b e-con-full e-flex e-con e-child\" data-id=\"274224b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd277e elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"3fd277e\" data-element_type=\"widget\" data-e-type=\"widget\" pascal=\"\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pascal Loyacono<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfc920e elementor-widget elementor-widget-heading\" data-id=\"bfc920e\" data-element_type=\"widget\" data-e-type=\"widget\" directeur=\"\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Directeur des ventes<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b37da60 e-con-full e-flex e-con e-child\" data-id=\"b37da60\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-edc0277 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"edc0277\" data-element_type=\"widget\" data-e-type=\"widget\" africa=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:africa@b-w-international.com\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"mail\"><mask id=\"mask0_31_3785\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"25\"><rect id=\"Bounding box\" y=\"0.5\" width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_31_3785)\"><path id=\"mail_2\" d=\"M2.5 20V5H21.5V20H2.5ZM12 13.0577L4 7.94225V18.5H20V7.94225L12 13.0577ZM12 11.5L19.8463 6.5H4.15375L12 11.5ZM4 7.94225V6.5V18.5V7.94225Z\" fill=\"#009FDF\"><\/path><\/g><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">E-mail<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d7a096 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6d7a096\" data-element_type=\"widget\" data-e-type=\"widget\" tel=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:+212655922692\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"call\"><mask id=\"mask0_31_3775\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"25\"><rect id=\"Bounding box\" y=\"0.5\" width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_31_3775)\"><path id=\"call_2\" d=\"M19.575 21C17.6327 21 15.6983 20.5676 13.772 19.7028C11.8458 18.8381 10.0847 17.6077 8.4885 16.0115C6.89883 14.4153 5.67 12.6535 4.802 10.726C3.934 8.7985 3.5 6.86483 3.5 4.925V4H8.66925L9.55575 8.55375L6.78275 11.2462C7.19425 11.9667 7.63458 12.6363 8.10375 13.2548C8.57308 13.8734 9.06925 14.4392 9.59225 14.952C10.1013 15.4738 10.6673 15.9668 11.2905 16.4308C11.9135 16.8949 12.6064 17.3411 13.3693 17.7693L16.125 14.9655L20.5 15.8558V21H19.575ZM6.073 9.827L7.94425 8.04225L7.44225 5.5H5.0155C5.06667 6.25633 5.18042 6.99258 5.35675 7.70875C5.53308 8.42475 5.77183 9.13083 6.073 9.827ZM14.773 18.4693C15.414 18.7654 16.0977 18.9984 16.824 19.1683C17.5503 19.3381 18.2757 19.4384 19 19.4693V17.0673L16.6307 16.5922L14.773 18.4693Z\" fill=\"#009FDF\"><\/path><\/g><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">+212 655 92 26 92<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"17651\" class=\"elementor elementor-17651 elementor-2696 elementor-2696 e-loop-item e-loop-item-22045 post-22045 team type-team status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-589ac91 e-con-full e-flex e-con e-parent\" data-id=\"589ac91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-817681c e-con-full e-flex e-con e-child\" data-id=\"817681c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-596f3cf elementor-widget elementor-widget-text-editor\" data-id=\"596f3cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tMallette de soufflage\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e54e1c elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9e54e1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/10\/profilbild-roberto-velasco-2024-bw-international.jpg\" class=\"attachment-full size-full wp-image-22042\" alt=\"Portrait de Roberto Velasco, v\u00eatu d&apos;un polo noir arborant le logo de B&amp;W International, les bras crois\u00e9s et arborant un sourire amical, dans un bureau moderne.\" srcset=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/10\/profilbild-roberto-velasco-2024-bw-international.jpg 500w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/10\/profilbild-roberto-velasco-2024-bw-international-300x300.jpg 300w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/10\/profilbild-roberto-velasco-2024-bw-international-150x150.jpg 150w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/10\/profilbild-roberto-velasco-2024-bw-international-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-274224b e-con-full e-flex e-con e-child\" data-id=\"274224b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd277e elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"3fd277e\" data-element_type=\"widget\" data-e-type=\"widget\" roberto=\"\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Roberto Velasco<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfc920e elementor-widget elementor-widget-heading\" data-id=\"bfc920e\" data-element_type=\"widget\" data-e-type=\"widget\" directeur=\"\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Directeur des ventes Espagne<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b37da60 e-con-full e-flex e-con e-child\" data-id=\"b37da60\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-edc0277 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"edc0277\" data-element_type=\"widget\" data-e-type=\"widget\" roberto=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:roberto.velasco@b-w-international.com\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"mail\"><mask id=\"mask0_31_3785\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"25\"><rect id=\"Bounding box\" y=\"0.5\" width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_31_3785)\"><path id=\"mail_2\" d=\"M2.5 20V5H21.5V20H2.5ZM12 13.0577L4 7.94225V18.5H20V7.94225L12 13.0577ZM12 11.5L19.8463 6.5H4.15375L12 11.5ZM4 7.94225V6.5V18.5V7.94225Z\" fill=\"#009FDF\"><\/path><\/g><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">E-mail<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d7a096 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6d7a096\" data-element_type=\"widget\" data-e-type=\"widget\" tel=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:+34689661889\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"call\"><mask id=\"mask0_31_3775\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"25\"><rect id=\"Bounding box\" y=\"0.5\" width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_31_3775)\"><path id=\"call_2\" d=\"M19.575 21C17.6327 21 15.6983 20.5676 13.772 19.7028C11.8458 18.8381 10.0847 17.6077 8.4885 16.0115C6.89883 14.4153 5.67 12.6535 4.802 10.726C3.934 8.7985 3.5 6.86483 3.5 4.925V4H8.66925L9.55575 8.55375L6.78275 11.2462C7.19425 11.9667 7.63458 12.6363 8.10375 13.2548C8.57308 13.8734 9.06925 14.4392 9.59225 14.952C10.1013 15.4738 10.6673 15.9668 11.2905 16.4308C11.9135 16.8949 12.6064 17.3411 13.3693 17.7693L16.125 14.9655L20.5 15.8558V21H19.575ZM6.073 9.827L7.94425 8.04225L7.44225 5.5H5.0155C5.06667 6.25633 5.18042 6.99258 5.35675 7.70875C5.53308 8.42475 5.77183 9.13083 6.073 9.827ZM14.773 18.4693C15.414 18.7654 16.0977 18.9984 16.824 19.1683C17.5503 19.3381 18.2757 19.4384 19 19.4693V17.0673L16.6307 16.5922L14.773 18.4693Z\" fill=\"#009FDF\"><\/path><\/g><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">+34 689 661 889<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a25cae3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a25cae3\" data-element_type=\"widget\" data-e-type=\"widget\" roberto=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.linkedin.com\/in\/robertovelascoa\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"icon-linkedin\" clip-path=\"url(#clip0_31_3795)\"><path id=\"Vector\" d=\"M24 3.83333C24 3.79333 24 3.76 24 3.72C23.9706 2.85574 23.6065 2.03672 22.9845 1.43591C22.3625 0.835091 21.5314 0.499501 20.6667 0.500001H3.33333C2.44928 0.500001 1.60143 0.85119 0.976311 1.47631C0.35119 2.10143 5.57857e-07 2.94928 5.57857e-07 3.83333V21.1667C-0.000499416 22.0314 0.335091 22.8625 0.935907 23.4845C1.53672 24.1065 2.35574 24.4706 3.22 24.5H3.33333H20.6667H20.8067C21.6426 24.4656 22.4349 24.1181 23.0265 23.5265C23.6181 22.9349 23.9656 22.1426 24 21.3067C24 21.26 24 21.2133 24 21.1667V3.83333ZM22 21.1667C22 21.5203 21.8595 21.8594 21.6095 22.1095C21.3594 22.3595 21.0203 22.5 20.6667 22.5H3.33333C2.97971 22.5 2.64057 22.3595 2.39052 22.1095C2.14048 21.8594 2 21.5203 2 21.1667V3.83333C2 3.47971 2.14048 3.14057 2.39052 2.89052C2.64057 2.64048 2.97971 2.5 3.33333 2.5H20.6667C21.0203 2.5 21.3594 2.64048 21.6095 2.89052C21.8595 3.14057 22 3.47971 22 3.83333V21.1667Z\" fill=\"#009FDF\"><\/path><path id=\"Vector_2\" d=\"M8.29309 6.75977H5.91309V8.95977H8.29309V6.75977Z\" fill=\"#009FDF\"><\/path><path id=\"Vector_3\" d=\"M8.29309 10.1797H5.91309V19.1664H8.29309V10.1797Z\" fill=\"#009FDF\"><\/path><path id=\"Vector_4\" d=\"M18.307 10.9797C18.0488 10.6611 17.7139 10.4134 17.3337 10.2597C16.8794 10.0632 16.3886 9.96553 15.8937 9.97306C15.3136 9.9692 14.7413 10.1061 14.2258 10.372C13.7102 10.6379 13.2669 11.0249 12.9337 11.4997V10.1664H10.707V19.1664H13.087V15.0931C13.0551 14.4014 13.1156 13.7087 13.267 13.0331C13.3844 12.668 13.6187 12.3517 13.9337 12.1331C14.2605 11.9068 14.6496 11.788 15.047 11.7931C15.3388 11.7848 15.6258 11.8687 15.867 12.0331C16.1006 12.1962 16.2759 12.4298 16.367 12.6997C16.5013 13.3191 16.5528 13.9535 16.5204 14.5864V19.1664H18.8937V13.5797C18.9085 13.0434 18.866 12.507 18.767 11.9797C18.6849 11.618 18.5282 11.2774 18.307 10.9797Z\" fill=\"#009FDF\"><\/path><\/g><defs><clipPath id=\"clip0_31_3795\"><rect width=\"24\" height=\"24\" fill=\"white\" transform=\"translate(0 0.5)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LinkedIn<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"17651\" class=\"elementor elementor-17651 elementor-2696 elementor-2696 e-loop-item e-loop-item-22909 post-22909 team type-team status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-589ac91 e-con-full e-flex e-con e-parent\" data-id=\"589ac91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-817681c e-con-full e-flex e-con e-child\" data-id=\"817681c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-596f3cf elementor-widget elementor-widget-text-editor\" data-id=\"596f3cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tIndustrie, Ext\u00e9rieur, Mallettes de soufflage\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e54e1c elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"9e54e1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/12\/profilbild-florent-brosse-2024-bw-international.jpg\" class=\"attachment-full size-full wp-image-22900\" alt=\"Un homme aux cheveux fonc\u00e9s et barbu, v\u00eatu d&apos;un sweat \u00e0 capuche noir de la marque B&amp;W International, se tient les bras crois\u00e9s et sourit dans un bureau moderne.\" srcset=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/12\/profilbild-florent-brosse-2024-bw-international.jpg 500w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/12\/profilbild-florent-brosse-2024-bw-international-300x300.jpg 300w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/12\/profilbild-florent-brosse-2024-bw-international-150x150.jpg 150w, https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/12\/profilbild-florent-brosse-2024-bw-international-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-274224b e-con-full e-flex e-con e-child\" data-id=\"274224b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd277e elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"3fd277e\" data-element_type=\"widget\" data-e-type=\"widget\" florent=\"\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Florent Brosse<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfc920e elementor-widget elementor-widget-heading\" data-id=\"bfc920e\" data-element_type=\"widget\" data-e-type=\"widget\" directeur=\"\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Directeur commercial senior France<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b37da60 e-con-full e-flex e-con e-child\" data-id=\"b37da60\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-edc0277 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"edc0277\" data-element_type=\"widget\" data-e-type=\"widget\" florent=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:florent.brosse@b-w-international.com\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"mail\"><mask id=\"mask0_31_3785\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"25\"><rect id=\"Bounding box\" y=\"0.5\" width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_31_3785)\"><path id=\"mail_2\" d=\"M2.5 20V5H21.5V20H2.5ZM12 13.0577L4 7.94225V18.5H20V7.94225L12 13.0577ZM12 11.5L19.8463 6.5H4.15375L12 11.5ZM4 7.94225V6.5V18.5V7.94225Z\" fill=\"#009FDF\"><\/path><\/g><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">E-mail<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d7a096 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6d7a096\" data-element_type=\"widget\" data-e-type=\"widget\" tel=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:+4982457899622\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"call\"><mask id=\"mask0_31_3775\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"25\"><rect id=\"Bounding box\" y=\"0.5\" width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask0_31_3775)\"><path id=\"call_2\" d=\"M19.575 21C17.6327 21 15.6983 20.5676 13.772 19.7028C11.8458 18.8381 10.0847 17.6077 8.4885 16.0115C6.89883 14.4153 5.67 12.6535 4.802 10.726C3.934 8.7985 3.5 6.86483 3.5 4.925V4H8.66925L9.55575 8.55375L6.78275 11.2462C7.19425 11.9667 7.63458 12.6363 8.10375 13.2548C8.57308 13.8734 9.06925 14.4392 9.59225 14.952C10.1013 15.4738 10.6673 15.9668 11.2905 16.4308C11.9135 16.8949 12.6064 17.3411 13.3693 17.7693L16.125 14.9655L20.5 15.8558V21H19.575ZM6.073 9.827L7.94425 8.04225L7.44225 5.5H5.0155C5.06667 6.25633 5.18042 6.99258 5.35675 7.70875C5.53308 8.42475 5.77183 9.13083 6.073 9.827ZM14.773 18.4693C15.414 18.7654 16.0977 18.9984 16.824 19.1683C17.5503 19.3381 18.2757 19.4384 19 19.4693V17.0673L16.6307 16.5922L14.773 18.4693Z\" fill=\"#009FDF\"><\/path><\/g><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">+49 8245 78 99 62 2<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a25cae3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a25cae3\" data-element_type=\"widget\" data-e-type=\"widget\" florent=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/de.linkedin.com\/in\/florent-brosse-8aa10245\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><g id=\"icon-linkedin\" clip-path=\"url(#clip0_31_3795)\"><path id=\"Vector\" d=\"M24 3.83333C24 3.79333 24 3.76 24 3.72C23.9706 2.85574 23.6065 2.03672 22.9845 1.43591C22.3625 0.835091 21.5314 0.499501 20.6667 0.500001H3.33333C2.44928 0.500001 1.60143 0.85119 0.976311 1.47631C0.35119 2.10143 5.57857e-07 2.94928 5.57857e-07 3.83333V21.1667C-0.000499416 22.0314 0.335091 22.8625 0.935907 23.4845C1.53672 24.1065 2.35574 24.4706 3.22 24.5H3.33333H20.6667H20.8067C21.6426 24.4656 22.4349 24.1181 23.0265 23.5265C23.6181 22.9349 23.9656 22.1426 24 21.3067C24 21.26 24 21.2133 24 21.1667V3.83333ZM22 21.1667C22 21.5203 21.8595 21.8594 21.6095 22.1095C21.3594 22.3595 21.0203 22.5 20.6667 22.5H3.33333C2.97971 22.5 2.64057 22.3595 2.39052 22.1095C2.14048 21.8594 2 21.5203 2 21.1667V3.83333C2 3.47971 2.14048 3.14057 2.39052 2.89052C2.64057 2.64048 2.97971 2.5 3.33333 2.5H20.6667C21.0203 2.5 21.3594 2.64048 21.6095 2.89052C21.8595 3.14057 22 3.47971 22 3.83333V21.1667Z\" fill=\"#009FDF\"><\/path><path id=\"Vector_2\" d=\"M8.29309 6.75977H5.91309V8.95977H8.29309V6.75977Z\" fill=\"#009FDF\"><\/path><path id=\"Vector_3\" d=\"M8.29309 10.1797H5.91309V19.1664H8.29309V10.1797Z\" fill=\"#009FDF\"><\/path><path id=\"Vector_4\" d=\"M18.307 10.9797C18.0488 10.6611 17.7139 10.4134 17.3337 10.2597C16.8794 10.0632 16.3886 9.96553 15.8937 9.97306C15.3136 9.9692 14.7413 10.1061 14.2258 10.372C13.7102 10.6379 13.2669 11.0249 12.9337 11.4997V10.1664H10.707V19.1664H13.087V15.0931C13.0551 14.4014 13.1156 13.7087 13.267 13.0331C13.3844 12.668 13.6187 12.3517 13.9337 12.1331C14.2605 11.9068 14.6496 11.788 15.047 11.7931C15.3388 11.7848 15.6258 11.8687 15.867 12.0331C16.1006 12.1962 16.2759 12.4298 16.367 12.6997C16.5013 13.3191 16.5528 13.9535 16.5204 14.5864V19.1664H18.8937V13.5797C18.9085 13.0434 18.866 12.507 18.767 11.9797C18.6849 11.618 18.5282 11.2774 18.307 10.9797Z\" fill=\"#009FDF\"><\/path><\/g><defs><clipPath id=\"clip0_31_3795\"><rect width=\"24\" height=\"24\" fill=\"white\" transform=\"translate(0 0.5)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LinkedIn<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8987137 e-flex e-con-boxed e-con e-parent\" data-id=\"8987137\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a10059 elementor-widget elementor-widget-ucaddon_titel_text_custom\" data-id=\"5a10059\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_titel_text_custom.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Custom Titel Text Button -->\n<style>\/* widget: Custom Titel Text Button *\/\n\n.uc_titel_text_custom_elementor_5a10059.container-titel-text .titel-container{\n  text-align: center;\n}\n\n.uc_titel_text_custom_elementor_5a10059.container-titel-text .text-container{\n  text-align: center;\n}\n\n.uc_titel_text_custom_elementor_5a10059.container-titel-text{\n\tdisplay:flex;\n  \tflex-direction:column;\n}\n\n<\/style>\n\n<div class=\"uc_titel_text_custom_elementor_5a10059 container-titel-text\">\n      <div class=\"titel-container\">\n     \n        <h2><span  class=\"uc_style_titel_text_custom_elementor_custom_titel_text_titel\" style=\"color:#009FDF;\">Demande g\u00e9n\u00e9rale<\/span><\/h2>  \n        <\/div>\n        <div class=\"text-container\">    \n       \n          <p>Vous avez une question sp\u00e9cifique, vous avez besoin d'une pi\u00e8ce de rechange, vous voulez faire une r\u00e9clamation sur un produit ou vous souhaitez en savoir plus sur B&amp;W ? N'h\u00e9sitez pas \u00e0 nous contacter via ce formulaire. Nos collaborateurs vous r\u00e9pondront dans les plus brefs d\u00e9lais.  <\/p>\n           <\/div>\n    \n  <\/div>\n<!-- end Custom Titel Text Button -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b58004 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9b58004\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/2fqwoo.share-eu1.hsforms.com\/2EPY-lyzJQiCuQNrhOFWC1Q\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VERS LE FORMULAIRE DE CONTACT<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69ae4c2 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"69ae4c2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0194bd2 elementor-widget elementor-widget-html\" data-id=\"0194bd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div class=\"hs-form-frame\" data-region=\"eu1\" data-form-id=\"8b70b745-c027-4006-908f-c4a0c800175c\" data-portal-id=\"147382008\"><\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contacts internationaux Nos interlocuteurs internationaux sont \u00e0 votre service dans le monde entier.Quel que soit l&rsquo;endroit du monde o\u00f9 vous souhaitez utiliser nos produits, nous sommes \u00e0 vos c\u00f4t\u00e9s gr\u00e2ce \u00e0 un solide r\u00e9seau d&rsquo;interlocuteurs internationaux. Que vous ayez besoin de d\u00e9tails techniques, que vous recherchiez les accessoires ad\u00e9quats ou que vous souhaitiez obtenir des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":17567,"menu_order":168,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-17599","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<title>International - B&amp;W Cases of Success<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/fr\/contact\/international\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"International - B&amp;W Cases of Success\" \/>\n<meta property=\"og:description\" content=\"Contacts internationaux Nos interlocuteurs internationaux sont \u00e0 votre service dans le monde entier.Quel que soit l&rsquo;endroit du monde o\u00f9 vous souhaitez utiliser nos produits, nous sommes \u00e0 vos c\u00f4t\u00e9s gr\u00e2ce \u00e0 un solide r\u00e9seau d&rsquo;interlocuteurs internationaux. Que vous ayez besoin de d\u00e9tails techniques, que vous recherchiez les accessoires ad\u00e9quats ou que vous souhaitiez obtenir des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/fr\/contact\/international\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T06:41:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1067\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/contact\\\/international\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/contact\\\/international\\\/\",\"name\":\"International - B&amp;W Cases of Success\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\"},\"datePublished\":\"2025-01-27T08:04:26+00:00\",\"dateModified\":\"2026-08-28T06:41:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/contact\\\/international\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/contact\\\/international\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/contact\\\/international\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/contact\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"International\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"International - B&amp;W Cases of Success","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/fr\/contact\/international\/","og_locale":"fr_FR","og_type":"article","og_title":"International - B&amp;W Cases of Success","og_description":"Contacts internationaux Nos interlocuteurs internationaux sont \u00e0 votre service dans le monde entier.Quel que soit l&rsquo;endroit du monde o\u00f9 vous souhaitez utiliser nos produits, nous sommes \u00e0 vos c\u00f4t\u00e9s gr\u00e2ce \u00e0 un solide r\u00e9seau d&rsquo;interlocuteurs internationaux. Que vous ayez besoin de d\u00e9tails techniques, que vous recherchiez les accessoires ad\u00e9quats ou que vous souhaitiez obtenir des [&hellip;]","og_url":"https:\/\/www.b-w-cases-of-success.com\/fr\/contact\/international\/","og_site_name":"B&amp;W Cases of Success","article_modified_time":"2026-08-28T06:41:42+00:00","og_image":[{"width":1067,"height":1067,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/contact\/international\/","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/contact\/international\/","name":"International - B&amp;W Cases of Success","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website"},"datePublished":"2025-01-27T08:04:26+00:00","dateModified":"2026-08-28T06:41:42+00:00","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/contact\/international\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.b-w-cases-of-success.com\/fr\/contact\/international\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/contact\/international\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/page-daccueil\/"},{"@type":"ListItem","position":2,"name":"Contact","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/contact\/"},{"@type":"ListItem","position":3,"name":"International"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/pages\/17599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/comments?post=17599"}],"version-history":[{"count":9,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/pages\/17599\/revisions"}],"predecessor-version":[{"id":29645,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/pages\/17599\/revisions\/29645"}],"up":[{"embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/pages\/17567"}],"wp:attachment":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/media?parent=17599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}