{"id":14569,"date":"2025-05-05T09:55:23","date_gmt":"2025-05-05T07:55:23","guid":{"rendered":"httpsss:\/\/dev.b-w-cases-of-success.de\/produkt\/energy-case-prox-1500-ac-300w-mallette-energie-bw\/"},"modified":"2025-11-04T09:22:57","modified_gmt":"2025-11-04T08:22:57","slug":"energy-case-prox-1500-ac-300w","status":"publish","type":"product","link":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/energy-case-prox-1500-ac-300w\/","title":{"rendered":"energy.case PROX 1500 AC 300W | Mallette \u00e9nergie B&amp;W"},"content":{"rendered":"<div>\n<ul>\n<li>Le B&amp;W energy.case offre une alimentation \u00e9lectrique fiable et flexible pour les applications professionnelles. Con\u00e7ue pour r\u00e9pondre aux exigences les plus strictes, elle est robuste, r\u00e9sistante \u00e0 la temp\u00e9rature et \u00e9tanche. Son utilisation est intuitive et simple.  <\/li>\n<li>Robuste et \u00e9tanche<\/li>\n<li>Syst\u00e8me de batterie puissant<\/li>\n<li>Fabriqu\u00e9 en Allemagne<\/li>\n<li>Possibilit\u00e9s de chargement flexibles<\/li>\n<li>Connexions multiples<\/li>\n<li>Manuel d&rsquo;utilisation avec NFC<\/li>\n<li>Courant continu &amp; alternatif<\/li>\n<li>Personnalisable<\/li>\n<li>Plus d&rsquo;informations sur la personnalisation : <a href=\"https:\/\/dev.b-w-cases-of-success.de\/fr\/valises-personnalisees\/installations-techniques\/\">les installations techniques<\/a><\/li>\n<\/ul>\n<\/div>\n<div style=\"display:flex; gap:10px;justify-content:center\" class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend\">\n\t\t<a  href=\"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product\/14569\/?action=genpdf&amp;id=14569\" class=\"pgfw-single-pdf-download-button\" target=_blank><img src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/icon-download.svg\" title=\"G\u00e9n\u00e9rer un PDF\" style=\"width:auto; height:45px;\"><\/a>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Le B&amp;W energy.case offre une alimentation \u00e9lectrique fiable et flexible pour les applications professionnelles. Con\u00e7ue pour r\u00e9pondre aux exigences les plus strictes, elle est robuste, r\u00e9sistante \u00e0 la temp\u00e9rature et \u00e9tanche. Son utilisation est intuitive et simple. Robuste et \u00e9tanche Syst\u00e8me de batterie puissant Fabriqu\u00e9 en Allemagne Possibilit\u00e9s de chargement flexibles Connexions multiples Manuel d&rsquo;utilisation [&hellip;]<\/p>\n","protected":false},"featured_media":14526,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[158],"product_tag":[],"class_list":["post-14569","product","type-product","status-publish","has-post-thumbnail","product_features-2-oeillets-pour-cadenas","product_features-empilable","product_features-etanche-a-leau-etanche-a-la-poussiere-etanche-a-lair","product_features-extremement-robuste","product_features-garantie-de-2-ans","product_features-poignee-de-transport-caoutchoutee","product_features-resistant-a-la-temperature","product_features-roulettes","product_cat-mallette-energie","pa_ausgaenge-ac-fr","first","instock","product-type-simple"],"acf":[],"yoast_head":"<title>energy.case PROX 1500 AC 300W | Mallette \u00e9nergie B&amp;W - B&amp;W Cases of Success<\/title>\n<meta name=\"description\" content=\"B&amp;W Energy Case Pro \u2713Etanche \u00e0 l&#039;eau \u2713R\u00e9sistant aux chocs \u2713Etanche \u00e0 la poussi\u00e8re \u2713Incluant l&#039;onduleur \u2794 Consultez maintenant !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/energy-case-prox-1500-ac-300w\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"energy.case PROX 1500 AC 300W | Mallette \u00e9nergie B&amp;W - B&amp;W Cases of Success\" \/>\n<meta property=\"og:description\" content=\"B&amp;W Energy Case Pro \u2713Etanche \u00e0 l&#039;eau \u2713R\u00e9sistant aux chocs \u2713Etanche \u00e0 la poussi\u00e8re \u2713Incluant l&#039;onduleur \u2794 Consultez maintenant !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/energy-case-prox-1500-ac-300w\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-04T08:22:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/energy-case_PROX-1500-AC-300W_BG_closed-back-side_bw-international.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/energy-case-prox-1500-ac-300w\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/energy-case-prox-1500-ac-300w\\\/\",\"name\":\"energy.case PROX 1500 AC 300W | Mallette \u00e9nergie B&amp;W - B&amp;W Cases of Success\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/energy-case-prox-1500-ac-300w\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/energy-case-prox-1500-ac-300w\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/energy-case_PROX-1500-AC-300W_BG_closed-back-side_bw-international.jpg\",\"datePublished\":\"2025-05-05T07:55:23+00:00\",\"dateModified\":\"2025-11-04T08:22:57+00:00\",\"description\":\"B&W Energy Case Pro \u2713Etanche \u00e0 l'eau \u2713R\u00e9sistant aux chocs \u2713Etanche \u00e0 la poussi\u00e8re \u2713Incluant l'onduleur \u2794 Consultez maintenant !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/energy-case-prox-1500-ac-300w\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/energy-case-prox-1500-ac-300w\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/energy-case-prox-1500-ac-300w\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/energy-case_PROX-1500-AC-300W_BG_closed-back-side_bw-international.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/energy-case_PROX-1500-AC-300W_BG_closed-back-side_bw-international.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"Gr\u00fcner Energiekoffer von B&W International mit robustem Geh\u00e4use, R\u00e4dern und Anschlussm\u00f6glichkeiten f\u00fcr den sicheren Transport und Einsatz.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/energy-case-prox-1500-ac-300w\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mallette \u00e9nergie\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/mallette-energie\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"energy.case PROX 1500 AC 300W | Mallette \u00e9nergie B&amp;W\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"energy.case PROX 1500 AC 300W | Mallette \u00e9nergie B&amp;W - B&amp;W Cases of Success","description":"B&W Energy Case Pro \u2713Etanche \u00e0 l'eau \u2713R\u00e9sistant aux chocs \u2713Etanche \u00e0 la poussi\u00e8re \u2713Incluant l'onduleur \u2794 Consultez maintenant !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/energy-case-prox-1500-ac-300w\/","og_locale":"fr_FR","og_type":"article","og_title":"energy.case PROX 1500 AC 300W | Mallette \u00e9nergie B&amp;W - B&amp;W Cases of Success","og_description":"B&W Energy Case Pro \u2713Etanche \u00e0 l'eau \u2713R\u00e9sistant aux chocs \u2713Etanche \u00e0 la poussi\u00e8re \u2713Incluant l'onduleur \u2794 Consultez maintenant !","og_url":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/energy-case-prox-1500-ac-300w\/","og_site_name":"B&amp;W Cases of Success","article_modified_time":"2025-11-04T08:22:57+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/energy-case_PROX-1500-AC-300W_BG_closed-back-side_bw-international.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/energy-case-prox-1500-ac-300w\/","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/energy-case-prox-1500-ac-300w\/","name":"energy.case PROX 1500 AC 300W | Mallette \u00e9nergie B&amp;W - B&amp;W Cases of Success","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/energy-case-prox-1500-ac-300w\/#primaryimage"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/energy-case-prox-1500-ac-300w\/#primaryimage"},"thumbnailUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/energy-case_PROX-1500-AC-300W_BG_closed-back-side_bw-international.jpg","datePublished":"2025-05-05T07:55:23+00:00","dateModified":"2025-11-04T08:22:57+00:00","description":"B&W Energy Case Pro \u2713Etanche \u00e0 l'eau \u2713R\u00e9sistant aux chocs \u2713Etanche \u00e0 la poussi\u00e8re \u2713Incluant l'onduleur \u2794 Consultez maintenant !","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/energy-case-prox-1500-ac-300w\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/energy-case-prox-1500-ac-300w\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/energy-case-prox-1500-ac-300w\/#primaryimage","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/energy-case_PROX-1500-AC-300W_BG_closed-back-side_bw-international.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/energy-case_PROX-1500-AC-300W_BG_closed-back-side_bw-international.jpg","width":1920,"height":1920,"caption":"Gr\u00fcner Energiekoffer von B&W International mit robustem Geh\u00e4use, R\u00e4dern und Anschlussm\u00f6glichkeiten f\u00fcr den sicheren Transport und Einsatz."},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/energy-case-prox-1500-ac-300w\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/page-daccueil\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Mallette \u00e9nergie","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/mallette-energie\/"},{"@type":"ListItem","position":4,"name":"energy.case PROX 1500 AC 300W | Mallette \u00e9nergie B&amp;W"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product\/14569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/media\/14526"}],"wp:attachment":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/media?parent=14569"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_brand?post=14569"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_cat?post=14569"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_tag?post=14569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}