{"id":15277,"date":"2025-05-05T09:54:49","date_gmt":"2025-05-05T07:54:49","guid":{"rendered":"httpsss:\/\/dev.b-w-cases-of-success.de\/produkt\/bw-case-pp-117-bag-combinaison-du-sac-bw-et-dune-mallette-robuste-bw-a-usages-multiples\/"},"modified":"2025-11-04T10:17:04","modified_gmt":"2025-11-04T09:17:04","slug":"bw-case-pp-117-tex","status":"publish","type":"product","link":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/bw-case-pp-117-tex\/","title":{"rendered":"bw.case PP.117.TEX | Combinaison du sac B&amp;W et d&rsquo;une mallette robuste \u00e0 usages multiples B&amp;W"},"content":{"rendered":"<div>\n<ul>\n<li>Combinaison d&rsquo;un sac B&amp;W et d&rsquo;une mallette robuste \u00e0 usages multiples B&amp;W<\/li>\n<li>Mallette extr\u00eamement solide : bo\u00eetier en polypropyl\u00e8ne (PP)<\/li>\n<li>Certificat d&rsquo;homologation ONU<\/li>\n<li>Empilable<\/li>\n<li>Etanche \u00e0 la poussi\u00e8re<\/li>\n<li>\u00c9tanche (indice de protection IP 67)<\/li>\n<li>Stable en temp\u00e9rature de -30 \u00b0C \u00e0 +80 \u00b0C<\/li>\n<li>Apte au vol : valve automatique de compensation de la pression atmosph\u00e9rique<\/li>\n<li>2 \u0153illets pour cadenas (\u00d8 7 mm)<\/li>\n<li>Poign\u00e9e caoutchout\u00e9e<\/li>\n<li>Fermetures \u00e0 deux niveaux<\/li>\n<li>Charni\u00e8re de d\u00e9crochage en option pour le couvercle amovible<\/li>\n<li>Sac souple en polyester r\u00e9sistant \u00e0 l&rsquo;eau<\/li>\n<li>Fermeture \u00e0 glissi\u00e8re \u00e0 double sens facile \u00e0 ouvrir<\/li>\n<li>Compartimentage variable &#8211; configur\u00e9 pour le combo DJI Neo Fly More<\/li>\n<li>Deux poches en filet<\/li>\n<li>Une poche avant<\/li>\n<\/ul>\n<\/div>\n<div style=\"display:flex; gap:10px;justify-content:center\" class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend\">\n\t\t<a  href=\"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product\/15277\/?action=genpdf&amp;id=15277\" class=\"pgfw-single-pdf-download-button\" target=_blank><img src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/icon-download.svg\" title=\"G\u00e9n\u00e9rer un PDF\" style=\"width:auto; height:45px;\"><\/a>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Combinaison d&rsquo;un sac B&amp;W et d&rsquo;une mallette robuste \u00e0 usages multiples B&amp;W Mallette extr\u00eamement solide : bo\u00eetier en polypropyl\u00e8ne (PP) Certificat d&rsquo;homologation ONU Empilable Etanche \u00e0 la poussi\u00e8re \u00c9tanche (indice de protection IP 67) Stable en temp\u00e9rature de -30 \u00b0C \u00e0 +80 \u00b0C Apte au vol : valve automatique de compensation de la pression atmosph\u00e9rique [&hellip;]<\/p>\n","protected":false},"featured_media":13254,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[171,501],"product_tag":[],"class_list":["post-15277","product","type-product","status-publish","has-post-thumbnail","product_features-2-oeillets-pour-cadenas","product_features-aptitude-au-vol","product_features-empilable","product_features-etanche-a-leau-etanche-a-la-poussiere-etanche-a-lair","product_features-extremement-robuste","product_features-poignee-de-transport-caoutchoutee","product_features-resistant-a-la-temperature","product_cat-accessoires-mallette-multi-usages","product_cat-accessoires-photo-et-video","pa_farbe-bronze-vert","pa_farbe-jaune","pa_farbe-noir","pa_farbe-orange-fr","first","instock","product-type-variable"],"acf":[],"yoast_head":"<title>bw.case PP.117.TEX | Combinaison du sac B&amp;W et d&#039;une mallette robuste \u00e0 usages multiples B&amp;W - B&amp;W Cases of Success<\/title>\n<meta name=\"description\" content=\"Sacoche pour appareil photo B&amp;W \u2713R\u00e9sistant \u00e0 l&#039;eau \u2713R\u00e9sistant \u00e0 l&#039;usure \u2713Syst\u00e8me d&#039;organisation \u2713Coque rigide robuste \u2794 \u00c0 d\u00e9couvrir en ligne d\u00e8s maintenant !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/bw-case-pp-117-tex\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"bw.case PP.117.TEX | Combinaison du sac B&amp;W et d&#039;une mallette robuste \u00e0 usages multiples B&amp;W - B&amp;W Cases of Success\" \/>\n<meta property=\"og:description\" content=\"Sacoche pour appareil photo B&amp;W \u2713R\u00e9sistant \u00e0 l&#039;eau \u2713R\u00e9sistant \u00e0 l&#039;usure \u2713Syst\u00e8me d&#039;organisation \u2713Coque rigide robuste \u2794 \u00c0 d\u00e9couvrir en ligne d\u00e8s maintenant !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/bw-case-pp-117-tex\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-04T09:17:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/3000_tex-117_B_photo-set_RPD_bw-international.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/bw-case-pp-117-tex\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/bw-case-pp-117-tex\\\/\",\"name\":\"bw.case PP.117.TEX | Combinaison du sac B&amp;W et d'une mallette robuste \u00e0 usages multiples B&amp;W - B&amp;W Cases of Success\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/bw-case-pp-117-tex\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/bw-case-pp-117-tex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/3000_tex-117_B_photo-set_RPD_bw-international.jpg\",\"datePublished\":\"2025-05-05T07:54:49+00:00\",\"dateModified\":\"2025-11-04T09:17:04+00:00\",\"description\":\"Sacoche pour appareil photo B&W \u2713R\u00e9sistant \u00e0 l'eau \u2713R\u00e9sistant \u00e0 l'usure \u2713Syst\u00e8me d'organisation \u2713Coque rigide robuste \u2794 \u00c0 d\u00e9couvrir en ligne d\u00e8s maintenant !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/bw-case-pp-117-tex\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/bw-case-pp-117-tex\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/bw-case-pp-117-tex\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/3000_tex-117_B_photo-set_RPD_bw-international.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/3000_tex-117_B_photo-set_RPD_bw-international.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"B&amp;W International Combinaison d'une mallette multi-usages PP 117 et d'un sac - mallette de protection imperm\u00e9able avec compartiments rembourr\u00e9s et bandouli\u00e8re pour transporter en toute s\u00e9curit\u00e9 des \u00e9quipements sensibles.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/bw-case-pp-117-tex\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mallette multi-usages\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/mallette-multi-usages\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Accessoires\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/mallette-multi-usages\\\/accessoires-mallette-multi-usages\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"bw.case PP.117.TEX | Combinaison du sac B&amp;W et d&rsquo;une mallette robuste \u00e0 usages multiples B&amp;W\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"bw.case PP.117.TEX | Combinaison du sac B&amp;W et d'une mallette robuste \u00e0 usages multiples B&amp;W - B&amp;W Cases of Success","description":"Sacoche pour appareil photo B&W \u2713R\u00e9sistant \u00e0 l'eau \u2713R\u00e9sistant \u00e0 l'usure \u2713Syst\u00e8me d'organisation \u2713Coque rigide robuste \u2794 \u00c0 d\u00e9couvrir en ligne d\u00e8s maintenant !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/bw-case-pp-117-tex\/","og_locale":"fr_FR","og_type":"article","og_title":"bw.case PP.117.TEX | Combinaison du sac B&amp;W et d'une mallette robuste \u00e0 usages multiples B&amp;W - B&amp;W Cases of Success","og_description":"Sacoche pour appareil photo B&W \u2713R\u00e9sistant \u00e0 l'eau \u2713R\u00e9sistant \u00e0 l'usure \u2713Syst\u00e8me d'organisation \u2713Coque rigide robuste \u2794 \u00c0 d\u00e9couvrir en ligne d\u00e8s maintenant !","og_url":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/bw-case-pp-117-tex\/","og_site_name":"B&amp;W Cases of Success","article_modified_time":"2025-11-04T09:17:04+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/3000_tex-117_B_photo-set_RPD_bw-international.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/bw-case-pp-117-tex\/","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/bw-case-pp-117-tex\/","name":"bw.case PP.117.TEX | Combinaison du sac B&amp;W et d'une mallette robuste \u00e0 usages multiples B&amp;W - B&amp;W Cases of Success","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/bw-case-pp-117-tex\/#primaryimage"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/bw-case-pp-117-tex\/#primaryimage"},"thumbnailUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/3000_tex-117_B_photo-set_RPD_bw-international.jpg","datePublished":"2025-05-05T07:54:49+00:00","dateModified":"2025-11-04T09:17:04+00:00","description":"Sacoche pour appareil photo B&W \u2713R\u00e9sistant \u00e0 l'eau \u2713R\u00e9sistant \u00e0 l'usure \u2713Syst\u00e8me d'organisation \u2713Coque rigide robuste \u2794 \u00c0 d\u00e9couvrir en ligne d\u00e8s maintenant !","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/bw-case-pp-117-tex\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/bw-case-pp-117-tex\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/bw-case-pp-117-tex\/#primaryimage","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/3000_tex-117_B_photo-set_RPD_bw-international.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/3000_tex-117_B_photo-set_RPD_bw-international.jpg","width":1920,"height":1920,"caption":"B&amp;W International Combinaison d'une mallette multi-usages PP 117 et d'un sac - mallette de protection imperm\u00e9able avec compartiments rembourr\u00e9s et bandouli\u00e8re pour transporter en toute s\u00e9curit\u00e9 des \u00e9quipements sensibles."},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/bw-case-pp-117-tex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/page-daccueil\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Mallette multi-usages","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/mallette-multi-usages\/"},{"@type":"ListItem","position":4,"name":"Accessoires","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/mallette-multi-usages\/accessoires-mallette-multi-usages\/"},{"@type":"ListItem","position":5,"name":"bw.case PP.117.TEX | Combinaison du sac B&amp;W et d&rsquo;une mallette robuste \u00e0 usages multiples B&amp;W"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product\/15277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/media\/13254"}],"wp:attachment":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/media?parent=15277"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_brand?post=15277"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_cat?post=15277"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_tag?post=15277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}