{"id":15474,"date":"2025-05-05T09:54:14","date_gmt":"2025-05-05T07:54:14","guid":{"rendered":"httpsss:\/\/dev.b-w-cases-of-success.de\/produkt\/wheel-bag-tex-22-bw-wheel-guard-l\/"},"modified":"2025-07-29T13:48:56","modified_gmt":"2025-07-29T11:48:56","slug":"wheel-bag-tex-22-wheel-guard-l","status":"publish","type":"product","link":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/wheel-bag-tex-22-wheel-guard-l\/","title":{"rendered":"wheel.bag TEX.22 | B&amp;W wheel.guard L"},"content":{"rendered":"<div>\n<ul>\n<li>Diam\u00e8tre : 790 mm<\/li>\n<li>Pour une roue jusqu&rsquo;\u00e0 29&Prime;, convient \u00e9galement aux roues \u00e0 profil extra-\u00e9pais<\/li>\n<li>Trois poches int\u00e9rieures<\/li>\n<li>Couleur : noir<\/li>\n<li>Mati\u00e8re : polyester<\/li>\n<\/ul>\n<\/div>\n<div style=\"display:flex; gap:10px;justify-content:center\" class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend\">\n\t\t<a  href=\"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product\/15474\/?action=genpdf&amp;id=15474\" class=\"pgfw-single-pdf-download-button\" target=_blank><img src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/icon-download.svg\" title=\"G\u00e9n\u00e9rer un PDF\" style=\"width:auto; height:45px;\"><\/a>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Diam\u00e8tre : 790 mm Pour une roue jusqu&rsquo;\u00e0 29&Prime;, convient \u00e9galement aux roues \u00e0 profil extra-\u00e9pais Trois poches int\u00e9rieures Couleur : noir Mati\u00e8re : polyester<\/p>\n","protected":false},"featured_media":14289,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[216,411],"product_tag":[],"class_list":["post-15474","product","type-product","status-publish","has-post-thumbnail","product_features-aptitude-au-vol","product_features-garantie-de-2-ans","product_cat-accessoires-velo","product_cat-valises-et-sacs-pour-le-transport-de-velos","pa_farbe-noir","first","instock","product-type-simple"],"acf":[],"yoast_head":"<title>wheel.bag TEX.22 | B&amp;W wheel.guard L - B&amp;W Cases of Success<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/wheel-bag-tex-22-wheel-guard-l\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"wheel.bag TEX.22 | B&amp;W wheel.guard L - B&amp;W Cases of Success\" \/>\n<meta property=\"og:description\" content=\"Diam\u00e8tre : 790 mm Pour une roue jusqu&rsquo;\u00e0 29&Prime;, convient \u00e9galement aux roues \u00e0 profil extra-\u00e9pais Trois poches int\u00e9rieures Couleur : noir Mati\u00e8re : polyester\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/wheel-bag-tex-22-wheel-guard-l\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-29T11:48:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/wheel-guard_L_tex-22_closed_bw-international.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/wheel-bag-tex-22-wheel-guard-l\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/wheel-bag-tex-22-wheel-guard-l\\\/\",\"name\":\"wheel.bag TEX.22 | B&amp;W wheel.guard L - B&amp;W Cases of Success\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/wheel-bag-tex-22-wheel-guard-l\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/wheel-bag-tex-22-wheel-guard-l\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/wheel-guard_L_tex-22_closed_bw-international.jpg\",\"datePublished\":\"2025-05-05T07:54:14+00:00\",\"dateModified\":\"2025-07-29T11:48:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/wheel-bag-tex-22-wheel-guard-l\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/wheel-bag-tex-22-wheel-guard-l\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/wheel-bag-tex-22-wheel-guard-l\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/wheel-guard_L_tex-22_closed_bw-international.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/wheel-guard_L_tex-22_closed_bw-international.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"Runde, schwarze TEX 22 Fahrradtasche von B&W Internationa mit Tragegriffen zum sicheren Transport von Laufr\u00e4dern und Fahrradteilen.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/wheel-bag-tex-22-wheel-guard-l\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Valises et sacs pour le transport de v\u00e9los\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/valises-et-sacs-pour-le-transport-de-velos\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Accessoires\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/valises-et-sacs-pour-le-transport-de-velos\\\/accessoires-velo\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"wheel.bag TEX.22 | B&amp;W wheel.guard L\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"wheel.bag TEX.22 | B&amp;W wheel.guard L - B&amp;W Cases of Success","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/wheel-bag-tex-22-wheel-guard-l\/","og_locale":"fr_FR","og_type":"article","og_title":"wheel.bag TEX.22 | B&amp;W wheel.guard L - B&amp;W Cases of Success","og_description":"Diam\u00e8tre : 790 mm Pour une roue jusqu&rsquo;\u00e0 29&Prime;, convient \u00e9galement aux roues \u00e0 profil extra-\u00e9pais Trois poches int\u00e9rieures Couleur : noir Mati\u00e8re : polyester","og_url":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/wheel-bag-tex-22-wheel-guard-l\/","og_site_name":"B&amp;W Cases of Success","article_modified_time":"2025-07-29T11:48:56+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/wheel-guard_L_tex-22_closed_bw-international.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/wheel-bag-tex-22-wheel-guard-l\/","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/wheel-bag-tex-22-wheel-guard-l\/","name":"wheel.bag TEX.22 | B&amp;W wheel.guard L - B&amp;W Cases of Success","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/wheel-bag-tex-22-wheel-guard-l\/#primaryimage"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/wheel-bag-tex-22-wheel-guard-l\/#primaryimage"},"thumbnailUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/wheel-guard_L_tex-22_closed_bw-international.jpg","datePublished":"2025-05-05T07:54:14+00:00","dateModified":"2025-07-29T11:48:56+00:00","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/wheel-bag-tex-22-wheel-guard-l\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/wheel-bag-tex-22-wheel-guard-l\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/wheel-bag-tex-22-wheel-guard-l\/#primaryimage","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/wheel-guard_L_tex-22_closed_bw-international.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/05\/wheel-guard_L_tex-22_closed_bw-international.jpg","width":1920,"height":1920,"caption":"Runde, schwarze TEX 22 Fahrradtasche von B&W Internationa mit Tragegriffen zum sicheren Transport von Laufr\u00e4dern und Fahrradteilen."},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/wheel-bag-tex-22-wheel-guard-l\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/page-daccueil\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Valises et sacs pour le transport de v\u00e9los","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/valises-et-sacs-pour-le-transport-de-velos\/"},{"@type":"ListItem","position":4,"name":"Accessoires","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/valises-et-sacs-pour-le-transport-de-velos\/accessoires-velo\/"},{"@type":"ListItem","position":5,"name":"wheel.bag TEX.22 | B&amp;W wheel.guard L"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product\/15474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/media\/14289"}],"wp:attachment":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/media?parent=15474"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_brand?post=15474"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_cat?post=15474"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_tag?post=15474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}