{"id":24728,"date":"2026-02-06T11:40:22","date_gmt":"2026-02-06T10:40:22","guid":{"rendered":"httpsss:\/\/dev.b-w-cases-of-success.de\/?post_type=product&#038;p=24728"},"modified":"2026-06-24T10:50:51","modified_gmt":"2026-06-24T08:50:51","slug":"cargo-case-hdpe-6100-6464","status":"publish","type":"product","link":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/cargo-case-hdpe-6100-6464\/","title":{"rendered":"cargo.case PE 6100.6464 | B&amp;W valise cargo dans de nombreuses tailles"},"content":{"rendered":"<div>\n<ul>\n<li>Cadre de valise extr\u00eamement robuste en PE haute performance r\u00e9sistant aux chocs<\/li>\n<li>Poign\u00e9es en polym\u00e8re tr\u00e8s r\u00e9sistantes avec prise en main ergonomique en caoutchouc<\/li>\n<li>Fermetures en acier inoxydable durables et tr\u00e8s r\u00e9sistantes<\/li>\n<li>Joint en silicone \u00e9tanche entre le cadre de la valise et le couvercle<\/li>\n<li>Particuli\u00e8rement r\u00e9sistant aux chocs et aux vibrations<\/li>\n<li>R\u00e9sistant aux UV et aux produits chimiques<\/li>\n<li>Rouleaux de bordure robustes en option pour une manipulation ais\u00e9e<\/li>\n<li>Con\u00e7u pour r\u00e9sister \u00e0 des temp\u00e9ratures extr\u00eames et \u00e0 un ensoleillement intense<\/li>\n<li>Int\u00e9rieur et incrustations personnalis\u00e9s disponibles<\/li>\n<li>Diff\u00e9rentes options de couleurs disponibles<\/li>\n<li>Empilage droit ou crois\u00e9 &#8211; m\u00eame avec des valises de tailles diff\u00e9rentes<\/li>\n<li>Certifi\u00e9 MIL-STD-810G, DEF STAN 81-41, STANAG 4280<\/li>\n<li>Etanche \u00e0 la poussi\u00e8re et \u00e0 l&rsquo;eau selon IP67<\/li>\n<\/ul>\n<p>Les cargo.cases sont \u00e9galement disponibles dans d&rsquo;autres couleurs sur demande.<br \/>\nPour un aper\u00e7u complet de toutes les tailles et configurations disponibles, veuillez consulter notre <a href=\"https:\/\/dev.b-w-cases-of-success.de\/fr\/?attachment_id=24601\" target=\"_blank\" rel=\"noopener\"><strong>Aper\u00e7u des produits<\/strong><\/a>.<\/p>\n<\/div>\n<div style=\"display:flex; gap:10px;justify-content:center\" class=\"wps-pgfw-pdf-generate-icon__wrapper-frontend\">\n\t\t<a  href=\"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product\/24728\/?action=genpdf&amp;id=24728\" class=\"pgfw-single-pdf-download-button\" target=_blank><img src=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/03\/icon-download.svg\" title=\"G\u00e9n\u00e9rer un PDF\" style=\"width:auto; height:45px;\"><\/a>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Cadre de valise extr\u00eamement robuste en PE haute performance r\u00e9sistant aux chocs Poign\u00e9es en polym\u00e8re tr\u00e8s r\u00e9sistantes avec prise en main ergonomique en caoutchouc Fermetures en acier inoxydable durables et tr\u00e8s r\u00e9sistantes Joint en silicone \u00e9tanche entre le cadre de la valise et le couvercle Particuli\u00e8rement r\u00e9sistant aux chocs et aux vibrations R\u00e9sistant aux UV [&hellip;]<\/p>\n","protected":false},"featured_media":24752,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[878,856],"product_tag":[],"class_list":["post-24728","product","type-product","status-publish","has-post-thumbnail","product_features-empilable","product_features-extremement-robuste","product_features-materiau-resistant","product_cat-cargo","product_cat-cargo-case","pa_farbe-bronze-vert","pa_farbe-jaune","pa_farbe-noir","pa_farbe-orange-fr","first","instock","product-type-variable"],"acf":[],"yoast_head":"<title>cargo.case PE 6100.6464 | B&amp;W valise cargo dans de nombreuses tailles - B&amp;W Cases of Success<\/title>\n<meta name=\"description\" content=\"Mallette polyvalente B&amp;W pratique \u2713R\u00e9sistante aux chocs \u2713Etanche \u00e0 l&#039;eau \u2713Avec poign\u00e9e de transport \u2713S\u00e9curit\u00e9 de la fermeture \u2794 Consultez maintenant !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/cargo-case-hdpe-6100-6464\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cargo.case PE 6100.6464 | B&amp;W valise cargo dans de nombreuses tailles - B&amp;W Cases of Success\" \/>\n<meta property=\"og:description\" content=\"Mallette polyvalente B&amp;W pratique \u2713R\u00e9sistante aux chocs \u2713Etanche \u00e0 l&#039;eau \u2713Avec poign\u00e9e de transport \u2713S\u00e9curit\u00e9 de la fermeture \u2794 Consultez maintenant !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/cargo-case-hdpe-6100-6464\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T08:50:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-6100-6464_closed_bw-international.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/cargo-case-hdpe-6100-6464\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/cargo-case-hdpe-6100-6464\\\/\",\"name\":\"cargo.case PE 6100.6464 | B&amp;W valise cargo dans de nombreuses tailles - B&amp;W Cases of Success\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/cargo-case-hdpe-6100-6464\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/cargo-case-hdpe-6100-6464\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cargo-case_HDPE-6100-6464_closed_bw-international.jpg\",\"datePublished\":\"2026-02-06T10:40:22+00:00\",\"dateModified\":\"2026-06-24T08:50:51+00:00\",\"description\":\"Mallette polyvalente B&W pratique \u2713R\u00e9sistante aux chocs \u2713Etanche \u00e0 l'eau \u2713Avec poign\u00e9e de transport \u2713S\u00e9curit\u00e9 de la fermeture \u2794 Consultez maintenant !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/cargo-case-hdpe-6100-6464\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/cargo-case-hdpe-6100-6464\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/cargo-case-hdpe-6100-6464\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cargo-case_HDPE-6100-6464_closed_bw-international.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cargo-case_HDPE-6100-6464_closed_bw-international.jpg\",\"width\":1920,\"height\":1920,\"caption\":\"La cargo.case HDPE 6100.6464 est une grande valise cargo B&amp;W noire avec des rainures horizontales et quatre fermetures frontales en plastique dur, repr\u00e9sent\u00e9e sur un fond blanc.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkt\\\/cargo-case-hdpe-6100-6464\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conteneurs de transport et de chargement\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/conteneurs-de-transport-et-de-chargement\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cargo cases\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/conteneurs-de-transport-et-de-chargement\\\/cargo-case\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"cargo.case PE 6100.6464 | B&amp;W valise cargo dans de nombreuses tailles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"cargo.case PE 6100.6464 | B&amp;W valise cargo dans de nombreuses tailles - B&amp;W Cases of Success","description":"Mallette polyvalente B&W pratique \u2713R\u00e9sistante aux chocs \u2713Etanche \u00e0 l'eau \u2713Avec poign\u00e9e de transport \u2713S\u00e9curit\u00e9 de la fermeture \u2794 Consultez maintenant !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/cargo-case-hdpe-6100-6464\/","og_locale":"fr_FR","og_type":"article","og_title":"cargo.case PE 6100.6464 | B&amp;W valise cargo dans de nombreuses tailles - B&amp;W Cases of Success","og_description":"Mallette polyvalente B&W pratique \u2713R\u00e9sistante aux chocs \u2713Etanche \u00e0 l'eau \u2713Avec poign\u00e9e de transport \u2713S\u00e9curit\u00e9 de la fermeture \u2794 Consultez maintenant !","og_url":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/cargo-case-hdpe-6100-6464\/","og_site_name":"B&amp;W Cases of Success","article_modified_time":"2026-06-24T08:50:51+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-6100-6464_closed_bw-international.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/cargo-case-hdpe-6100-6464\/","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/cargo-case-hdpe-6100-6464\/","name":"cargo.case PE 6100.6464 | B&amp;W valise cargo dans de nombreuses tailles - B&amp;W Cases of Success","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/cargo-case-hdpe-6100-6464\/#primaryimage"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/cargo-case-hdpe-6100-6464\/#primaryimage"},"thumbnailUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-6100-6464_closed_bw-international.jpg","datePublished":"2026-02-06T10:40:22+00:00","dateModified":"2026-06-24T08:50:51+00:00","description":"Mallette polyvalente B&W pratique \u2713R\u00e9sistante aux chocs \u2713Etanche \u00e0 l'eau \u2713Avec poign\u00e9e de transport \u2713S\u00e9curit\u00e9 de la fermeture \u2794 Consultez maintenant !","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/cargo-case-hdpe-6100-6464\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/cargo-case-hdpe-6100-6464\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/cargo-case-hdpe-6100-6464\/#primaryimage","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-6100-6464_closed_bw-international.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2026\/02\/cargo-case_HDPE-6100-6464_closed_bw-international.jpg","width":1920,"height":1920,"caption":"La cargo.case HDPE 6100.6464 est une grande valise cargo B&amp;W noire avec des rainures horizontales et quatre fermetures frontales en plastique dur, repr\u00e9sent\u00e9e sur un fond blanc."},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkt\/cargo-case-hdpe-6100-6464\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/page-daccueil\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Conteneurs de transport et de chargement","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/conteneurs-de-transport-et-de-chargement\/"},{"@type":"ListItem","position":4,"name":"Cargo cases","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/conteneurs-de-transport-et-de-chargement\/cargo-case\/"},{"@type":"ListItem","position":5,"name":"cargo.case PE 6100.6464 | B&amp;W valise cargo dans de nombreuses tailles"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product\/24728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/media\/24752"}],"wp:attachment":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/media?parent=24728"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_brand?post=24728"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_cat?post=24728"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_tag?post=24728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}