{"id":501,"count":24,"description":"","link":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/valises-pour-drones-et-appareils-photo\/accessoires-photo-et-video\/","name":"Accessoires","slug":"accessoires-photo-et-video","taxonomy":"product_cat","parent":68,"meta":[],"menu_order":20,"acf":[],"yoast_head":"<title>Zubeh\u00f6r Drohnen- &amp; Kamerakoffer | Medien &amp; Foto- und Videoproduktion<\/title>\n<meta name=\"description\" content=\"Foto- &amp; Videokoffer Zubeh\u00f6r: \u2713ma\u00dfgeschneiderte Schaumstoffeins\u00e4tze \u2713variable Facheinteilung \u2713praktische Tragegurte &amp; Taschen \u2794 Jetzt entdecken!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/valises-pour-drones-et-appareils-photo\/accessoires-photo-et-video\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zubeh\u00f6r Drohnen- &amp; Kamerakoffer | Medien &amp; Foto- und Videoproduktion\" \/>\n<meta property=\"og:description\" content=\"Foto- &amp; Videokoffer Zubeh\u00f6r: \u2713ma\u00dfgeschneiderte Schaumstoffeins\u00e4tze \u2713variable Facheinteilung \u2713praktische Tragegurte &amp; Taschen \u2794 Jetzt entdecken!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/valises-pour-drones-et-appareils-photo\/accessoires-photo-et-video\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1067\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/valises-pour-drones-et-appareils-photo\\\/accessoires-photo-et-video\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/valises-pour-drones-et-appareils-photo\\\/accessoires-photo-et-video\\\/\",\"name\":\"Zubeh\u00f6r Drohnen- & Kamerakoffer | Medien & Foto- und Videoproduktion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\"},\"description\":\"Foto- & Videokoffer Zubeh\u00f6r: \u2713ma\u00dfgeschneiderte Schaumstoffeins\u00e4tze \u2713variable Facheinteilung \u2713praktische Tragegurte & Taschen \u2794 Jetzt entdecken!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/valises-pour-drones-et-appareils-photo\\\/accessoires-photo-et-video\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/valises-pour-drones-et-appareils-photo\\\/accessoires-photo-et-video\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Valises pour drones et appareils photo\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/valises-pour-drones-et-appareils-photo\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Accessoires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"Zubeh\u00f6r Drohnen- & Kamerakoffer | Medien & Foto- und Videoproduktion","description":"Foto- & Videokoffer Zubeh\u00f6r: \u2713ma\u00dfgeschneiderte Schaumstoffeins\u00e4tze \u2713variable Facheinteilung \u2713praktische Tragegurte & Taschen \u2794 Jetzt entdecken!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/valises-pour-drones-et-appareils-photo\/accessoires-photo-et-video\/","og_locale":"fr_FR","og_type":"article","og_title":"Zubeh\u00f6r Drohnen- & Kamerakoffer | Medien & Foto- und Videoproduktion","og_description":"Foto- & Videokoffer Zubeh\u00f6r: \u2713ma\u00dfgeschneiderte Schaumstoffeins\u00e4tze \u2713variable Facheinteilung \u2713praktische Tragegurte & Taschen \u2794 Jetzt entdecken!","og_url":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/valises-pour-drones-et-appareils-photo\/accessoires-photo-et-video\/","og_site_name":"B&amp;W Cases of Success","og_image":[{"width":1067,"height":1067,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/valises-pour-drones-et-appareils-photo\/accessoires-photo-et-video\/","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/valises-pour-drones-et-appareils-photo\/accessoires-photo-et-video\/","name":"Zubeh\u00f6r Drohnen- & Kamerakoffer | Medien & Foto- und Videoproduktion","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website"},"description":"Foto- & Videokoffer Zubeh\u00f6r: \u2713ma\u00dfgeschneiderte Schaumstoffeins\u00e4tze \u2713variable Facheinteilung \u2713praktische Tragegurte & Taschen \u2794 Jetzt entdecken!","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/valises-pour-drones-et-appareils-photo\/accessoires-photo-et-video\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/valises-pour-drones-et-appareils-photo\/accessoires-photo-et-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/page-daccueil\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Valises pour drones et appareils photo","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/valises-pour-drones-et-appareils-photo\/"},{"@type":"ListItem","position":4,"name":"Accessoires"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_cat\/501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_cat\/68"}],"wp:post_type":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product?product_cat=501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}