{"id":882,"count":6,"description":"","link":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/rack\/","name":"Rack case","slug":"rack","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":23,"acf":[],"yoast_head":"<title>Rackkoffer von B&amp;W | F\u00fcr mobile Milit\u00e4rtechnik &amp; mehr<\/title>\n<meta name=\"description\" content=\"Rackkoffer von B&amp;W sch\u00fctzen empfindliche Technik im mobilen Einsatz \u2713 Ideal f\u00fcr Milit\u00e4r, Rettung, Luftfahrt &amp; Satcom. L\u00f6sungen f\u00fcr Unternehmen entdecken.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/rack\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rackkoffer von B&amp;W | F\u00fcr mobile Milit\u00e4rtechnik &amp; mehr\" \/>\n<meta property=\"og:description\" content=\"Rackkoffer von B&amp;W sch\u00fctzen empfindliche Technik im mobilen Einsatz \u2713 Ideal f\u00fcr Milit\u00e4r, Rettung, Luftfahrt &amp; Satcom. L\u00f6sungen f\u00fcr Unternehmen entdecken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/rack\/\" \/>\n<meta property=\"og:site_name\" content=\"B&amp;W Cases of Success\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1067\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/rack\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/rack\\\/\",\"name\":\"Rackkoffer von B&W | F\u00fcr mobile Milit\u00e4rtechnik & mehr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\"},\"description\":\"Rackkoffer von B&W sch\u00fctzen empfindliche Technik im mobilen Einsatz \u2713 Ideal f\u00fcr Milit\u00e4r, Rettung, Luftfahrt & Satcom. L\u00f6sungen f\u00fcr Unternehmen entdecken.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/rack\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/produkte\\\/rack\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rack case\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"name\":\"B&W Cases of Success\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#organization\",\"name\":\"B&W Cases of Success\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-bw-international-Cyan_RGB_quadrat.jpg\",\"width\":1067,\"height\":1067,\"caption\":\"B&W Cases of Success\"},\"image\":{\"@id\":\"https:\\\/\\\/www.b-w-cases-of-success.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"Rackkoffer von B&W | F\u00fcr mobile Milit\u00e4rtechnik & mehr","description":"Rackkoffer von B&W sch\u00fctzen empfindliche Technik im mobilen Einsatz \u2713 Ideal f\u00fcr Milit\u00e4r, Rettung, Luftfahrt & Satcom. L\u00f6sungen f\u00fcr Unternehmen entdecken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/rack\/","og_locale":"fr_FR","og_type":"article","og_title":"Rackkoffer von B&W | F\u00fcr mobile Milit\u00e4rtechnik & mehr","og_description":"Rackkoffer von B&W sch\u00fctzen empfindliche Technik im mobilen Einsatz \u2713 Ideal f\u00fcr Milit\u00e4r, Rettung, Luftfahrt & Satcom. L\u00f6sungen f\u00fcr Unternehmen entdecken.","og_url":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/rack\/","og_site_name":"B&amp;W Cases of Success","og_image":[{"width":1067,"height":1067,"url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/rack\/","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/rack\/","name":"Rackkoffer von B&W | F\u00fcr mobile Milit\u00e4rtechnik & mehr","isPartOf":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website"},"description":"Rackkoffer von B&W sch\u00fctzen empfindliche Technik im mobilen Einsatz \u2713 Ideal f\u00fcr Milit\u00e4r, Rettung, Luftfahrt & Satcom. L\u00f6sungen f\u00fcr Unternehmen entdecken.","breadcrumb":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/rack\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/produkte\/rack\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/page-daccueil\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.b-w-cases-of-success.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Rack case"}]},{"@type":"WebSite","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#website","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","name":"B&W Cases of Success","description":"","publisher":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b-w-cases-of-success.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#organization","name":"B&W Cases of Success","url":"https:\/\/www.b-w-cases-of-success.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","contentUrl":"https:\/\/www.b-w-cases-of-success.com\/wp-content\/uploads\/2025\/07\/Logo-bw-international-Cyan_RGB_quadrat.jpg","width":1067,"height":1067,"caption":"B&W Cases of Success"},"image":{"@id":"https:\/\/www.b-w-cases-of-success.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_cat\/882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.b-w-cases-of-success.com\/fr\/wp-json\/wp\/v2\/product?product_cat=882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}